{"id":10134,"date":"2015-07-13T07:22:12","date_gmt":"2015-07-13T07:22:12","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/"},"modified":"2015-07-13T07:22:12","modified_gmt":"2015-07-13T07:22:12","slug":"aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/","title":{"rendered":"Medallas de bronce para el deporte ciempozuele\u00f1o"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><em>Los deportistas Aar\u00f3n Cordero, Mateo Barriguete y Alejandro Mart\u00edn subieron al p\u00f3dium en los Campeonatos nacionales de sus respectivas disciplinas<\/em><\/p>\n<p style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px; text-align: justify;\">Este fin de semana est\u00e1 marcado por los \u00e9xitos deportivos de los j\u00f3venes de nuestro municipio.<\/p>\n<p style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Los ciempozuele\u00f1os Aar\u00f3n Cordero y Mateo Barriguete se hicieron con la medalla de bronce en el Campeonato de Espa\u00f1a de ciclismo en edad escolar que ha tenido lugar este fin de semana en la localidad murciana de Lorca. <\/span><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Los corredores, seleccionados en el equipo de la Comunidad de Madrid, lograron el tercer puesto en la prueba por equipos.<\/span><\/p>\n<p style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Por otro lado, <\/span><span style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px;\">Alejandro L\u00f3pez Mart\u00edn, natural de Ciempozuelos, ha conseguido la medalla de bronce en el XIV Campeonato Cadete de Espa\u00f1a de atletismo que se ha celebrado este fin de semana en Valladolid. Alejandro compiti\u00f3 en la modalidad de 1.000 metros que recorri\u00f3 en 2&#8242; 37&#8221; 02.<\/span><\/p>\n<p style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px;\"><span style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px;\">Este metal se suma a otros \u00e9xitos como el primer puesto en el Campeonato de clubes en 1.000 metros, el tercer clasificado en 3.000 pista exterior del Campeonato y el Campeonato de pista cubierta de 3.000 metros, todos ellos de Madrid.<\/span><\/p>\n<p style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px;\"><span style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px;\"><img decoding=\"async\" class=\" size-full wp-image-10133\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez.jpg\" border=\"0\" width=\"100%\" style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px;\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez-200x268.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez-224x300.jpg 224w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez-400x536.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez-600x803.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez-765x1024.jpg 765w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez-768x1028.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez-800x1071.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez-1147x1536.jpg 1147w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez.jpg 1195w\" sizes=\"(max-width: 1195px) 100vw, 1195px\" \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los deportistas Aar\u00f3n Cordero, Mateo Barriguete y Alejandro Mart\u00edn subieron al p\u00f3dium en los Campeonatos nacionales de sus respectivas disciplinas Este fin de semana est\u00e1 marcado por los \u00e9xitos deportivos de los j\u00f3venes de nuestro municipio. Los ciempozuele\u00f1os Aar\u00f3n Cordero y Mateo Barriguete se hicieron con la medalla de bronce en el Campeonato de Espa\u00f1a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1239],"class_list":["post-10134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-1239"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los deportistas Aar\u00f3n Cordero, Mateo Barriguete y Alejandro Mart\u00edn subieron al p\u00f3dium en los Campeonatos nacionales de sus respectivas disciplinas Este fin de semana est\u00e1 marcado por los \u00e9xitos deportivos de los j\u00f3venes de nuestro municipio. Los ciempozuele\u00f1os Aar\u00f3n Cordero y Mateo Barriguete se hicieron con la medalla de bronce en el Campeonato de Espa\u00f1a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Medallas de bronce para el deporte ciempozuele\u00f1o - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Los deportistas Aar\u00f3n Cordero, Mateo Barriguete y Alejandro Mart\u00edn subieron al p\u00f3dium en los Campeonatos nacionales de sus respectivas disciplinas Este fin de semana est\u00e1 marcado por los \u00e9xitos deportivos de los j\u00f3venes de nuestro municipio. Los ciempozuele\u00f1os Aar\u00f3n Cordero y Mateo Barriguete se hicieron con la medalla de bronce en el Campeonato de Espa\u00f1a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-07-13T07:22:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-07-13T07:22:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Medallas de bronce para el deporte ciempozuele\u00f1o - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los deportistas Aar\u00f3n Cordero, Mateo Barriguete y Alejandro Mart\u00edn subieron al p\u00f3dium en los Campeonatos nacionales de sus respectivas disciplinas Este fin de semana est\u00e1 marcado por los \u00e9xitos deportivos de los j\u00f3venes de nuestro municipio. Los ciempozuele\u00f1os Aar\u00f3n Cordero y Mateo Barriguete se hicieron con la medalla de bronce en el Campeonato de Espa\u00f1a\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#blogposting\",\"name\":\"Medallas de bronce para el deporte ciempozuele\\u00f1o - Ayuntamiento de Ciempozuelos\",\"headline\":\"Medallas de bronce para el deporte ciempozuele\\u00f1o\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/campeonato-atletismo-cadete.-bronce-alejandro-lpez.jpg\",\"width\":1195,\"height\":1600},\"datePublished\":\"2015-07-13T07:22:12+02:00\",\"dateModified\":\"2015-07-13T07:22:12+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#webpage\"},\"articleSection\":\"1086\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1086\\\/#listItem\",\"name\":\"1086\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1086\\\/#listItem\",\"position\":2,\"name\":\"1086\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1086\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#listItem\",\"name\":\"Medallas de bronce para el deporte ciempozuele\\u00f1o\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#listItem\",\"position\":3,\"name\":\"Medallas de bronce para el deporte ciempozuele\\u00f1o\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1086\\\/#listItem\",\"name\":\"1086\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/\",\"name\":\"Medallas de bronce para el deporte ciempozuele\\u00f1o - Ayuntamiento de Ciempozuelos\",\"description\":\"Los deportistas Aar\\u00f3n Cordero, Mateo Barriguete y Alejandro Mart\\u00edn subieron al p\\u00f3dium en los Campeonatos nacionales de sus respectivas disciplinas Este fin de semana est\\u00e1 marcado por los \\u00e9xitos deportivos de los j\\u00f3venes de nuestro municipio. Los ciempozuele\\u00f1os Aar\\u00f3n Cordero y Mateo Barriguete se hicieron con la medalla de bronce en el Campeonato de Espa\\u00f1a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/campeonato-atletismo-cadete.-bronce-alejandro-lpez.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#mainImage\",\"width\":1195,\"height\":1600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/13\\\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\\\/#mainImage\"},\"datePublished\":\"2015-07-13T07:22:12+02:00\",\"dateModified\":\"2015-07-13T07:22:12+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Medallas de bronce para el deporte ciempozuele\u00f1o - Ayuntamiento de Ciempozuelos","description":"Los deportistas Aar\u00f3n Cordero, Mateo Barriguete y Alejandro Mart\u00edn subieron al p\u00f3dium en los Campeonatos nacionales de sus respectivas disciplinas Este fin de semana est\u00e1 marcado por los \u00e9xitos deportivos de los j\u00f3venes de nuestro municipio. Los ciempozuele\u00f1os Aar\u00f3n Cordero y Mateo Barriguete se hicieron con la medalla de bronce en el Campeonato de Espa\u00f1a","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#blogposting","name":"Medallas de bronce para el deporte ciempozuele\u00f1o - Ayuntamiento de Ciempozuelos","headline":"Medallas de bronce para el deporte ciempozuele\u00f1o","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez.jpg","width":1195,"height":1600},"datePublished":"2015-07-13T07:22:12+02:00","dateModified":"2015-07-13T07:22:12+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#webpage"},"articleSection":"1086"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/#listItem","name":"1086"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/#listItem","position":2,"name":"1086","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#listItem","name":"Medallas de bronce para el deporte ciempozuele\u00f1o"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#listItem","position":3,"name":"Medallas de bronce para el deporte ciempozuele\u00f1o","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/#listItem","name":"1086"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/","name":"Medallas de bronce para el deporte ciempozuele\u00f1o - Ayuntamiento de Ciempozuelos","description":"Los deportistas Aar\u00f3n Cordero, Mateo Barriguete y Alejandro Mart\u00edn subieron al p\u00f3dium en los Campeonatos nacionales de sus respectivas disciplinas Este fin de semana est\u00e1 marcado por los \u00e9xitos deportivos de los j\u00f3venes de nuestro municipio. Los ciempozuele\u00f1os Aar\u00f3n Cordero y Mateo Barriguete se hicieron con la medalla de bronce en el Campeonato de Espa\u00f1a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/campeonato-atletismo-cadete.-bronce-alejandro-lpez.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#mainImage","width":1195,"height":1600},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/#mainImage"},"datePublished":"2015-07-13T07:22:12+02:00","dateModified":"2015-07-13T07:22:12+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Medallas de bronce para el deporte ciempozuele\u00f1o - Ayuntamiento de Ciempozuelos","og:description":"Los deportistas Aar\u00f3n Cordero, Mateo Barriguete y Alejandro Mart\u00edn subieron al p\u00f3dium en los Campeonatos nacionales de sus respectivas disciplinas Este fin de semana est\u00e1 marcado por los \u00e9xitos deportivos de los j\u00f3venes de nuestro municipio. Los ciempozuele\u00f1os Aar\u00f3n Cordero y Mateo Barriguete se hicieron con la medalla de bronce en el Campeonato de Espa\u00f1a","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/","article:published_time":"2015-07-13T07:22:12+00:00","article:modified_time":"2015-07-13T07:22:12+00:00","twitter:card":"summary","twitter:title":"Medallas de bronce para el deporte ciempozuele\u00f1o - Ayuntamiento de Ciempozuelos","twitter:description":"Los deportistas Aar\u00f3n Cordero, Mateo Barriguete y Alejandro Mart\u00edn subieron al p\u00f3dium en los Campeonatos nacionales de sus respectivas disciplinas Este fin de semana est\u00e1 marcado por los \u00e9xitos deportivos de los j\u00f3venes de nuestro municipio. Los ciempozuele\u00f1os Aar\u00f3n Cordero y Mateo Barriguete se hicieron con la medalla de bronce en el Campeonato de Espa\u00f1a"},"aioseo_meta_data":{"post_id":"10134","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:14:56","updated":"2025-06-04 16:45:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/\" title=\"1086\">1086<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMedallas de bronce para el deporte ciempozuele\u00f1o\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1086","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/"},{"label":"Medallas de bronce para el deporte ciempozuele\u00f1o","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/13\/aaron-cordero-y-mateo-barriguete-bronce-en-el-campeonato-de-espana-de-ciclismo\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:53:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10134"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10133"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}