{"id":10065,"date":"2015-06-29T10:47:07","date_gmt":"2015-06-29T10:47:07","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/"},"modified":"2015-06-29T10:47:07","modified_gmt":"2015-06-29T10:47:07","slug":"vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/","title":{"rendered":"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: left;\"><em>Este fin de semana arrancan las actividades culturales con el acto de bienvenida a dos ni\u00f1os saharuis y el espect\u00e1culo \u2018El alquimista del sonido\u2019<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\">Ciempozuelos inicia las actividades culturales programadas para este verano 2015 este s\u00e1bado, 4 de julio, a las 20.00 horas con el acto de bienvenida de dos ni\u00f1os saharauis que pasar\u00e1n las vacaciones estivales en nuestro municipio. Esta iniciativa est\u00e1 enmarcada en el proyecto Vacaciones en Paz.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\">La plaza Ventura Rodr\u00edguez ser\u00e1 el escenario de este evento en el que los asistentes m\u00e1s j\u00f3venes podr\u00e1n disfrutar de juegos y pintacaras y para el p\u00fablico adulto est\u00e1n programadas otras actividades como la ceremonia del t\u00e9 saharaui y la proyecci\u00f3n de un documental sobre la situaci\u00f3n del S\u00e1hara occidental para el p\u00fablico adulto. \u00a0Este acto contar\u00e1 con la presencia del delegado del Frente Polisario en Madrid.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\">El domingo 5 de julio el universo clown llenar\u00e1 la plaza de la Constituci\u00f3n de la mano del artista Fausto. A las 21.30 horas tendr\u00e1 lugar \u2018El alquimista del sonido\u2019, un espect\u00e1culo familiar, c\u00f3mico y participativo con instrumentos ins\u00f3litos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana arrancan las actividades culturales con el acto de bienvenida a dos ni\u00f1os saharuis y el espect\u00e1culo \u2018El alquimista del sonido\u2019 Ciempozuelos inicia las actividades culturales programadas para este verano 2015 este s\u00e1bado, 4 de julio, a las 20.00 horas con el acto de bienvenida de dos ni\u00f1os saharauis que pasar\u00e1n las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1217],"class_list":["post-10065","post","type-post","status-publish","format-standard","hentry","tag-1217"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Este fin de semana arrancan las actividades culturales con el acto de bienvenida a dos ni\u00f1os saharuis y el espect\u00e1culo \u2018El alquimista del sonido\u2019 Ciempozuelos inicia las actividades culturales programadas para este verano 2015 este s\u00e1bado, 4 de julio, a las 20.00 horas con el acto de bienvenida de dos ni\u00f1os saharauis que pasar\u00e1n las\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Este fin de semana arrancan las actividades culturales con el acto de bienvenida a dos ni\u00f1os saharuis y el espect\u00e1culo \u2018El alquimista del sonido\u2019 Ciempozuelos inicia las actividades culturales programadas para este verano 2015 este s\u00e1bado, 4 de julio, a las 20.00 horas con el acto de bienvenida de dos ni\u00f1os saharauis que pasar\u00e1n las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-06-29T10:47:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-06-29T10:47:07+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Este fin de semana arrancan las actividades culturales con el acto de bienvenida a dos ni\u00f1os saharuis y el espect\u00e1culo \u2018El alquimista del sonido\u2019 Ciempozuelos inicia las actividades culturales programadas para este verano 2015 este s\u00e1bado, 4 de julio, a las 20.00 horas con el acto de bienvenida de dos ni\u00f1os saharauis que pasar\u00e1n las\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/29\\\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\\\/#blogposting\",\"name\":\"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-06-29T10:47:07+02:00\",\"dateModified\":\"2015-06-29T10:47:07+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/29\\\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/29\\\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\\\/#webpage\"},\"articleSection\":\"1139\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/29\\\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"position\":2,\"name\":\"1139\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/29\\\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\\\/#listItem\",\"name\":\"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/29\\\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\\\/#listItem\",\"position\":3,\"name\":\"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/29\\\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/29\\\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/29\\\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\\\/\",\"name\":\"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"Este fin de semana arrancan las actividades culturales con el acto de bienvenida a dos ni\\u00f1os saharuis y el espect\\u00e1culo \\u2018El alquimista del sonido\\u2019 Ciempozuelos inicia las actividades culturales programadas para este verano 2015 este s\\u00e1bado, 4 de julio, a las 20.00 horas con el acto de bienvenida de dos ni\\u00f1os saharauis que pasar\\u00e1n las\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/29\\\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-06-29T10:47:07+02:00\",\"dateModified\":\"2015-06-29T10:47:07+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"Este fin de semana arrancan las actividades culturales con el acto de bienvenida a dos ni\u00f1os saharuis y el espect\u00e1culo \u2018El alquimista del sonido\u2019 Ciempozuelos inicia las actividades culturales programadas para este verano 2015 este s\u00e1bado, 4 de julio, a las 20.00 horas con el acto de bienvenida de dos ni\u00f1os saharauis que pasar\u00e1n las","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/#blogposting","name":"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-06-29T10:47:07+02:00","dateModified":"2015-06-29T10:47:07+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/#webpage"},"articleSection":"1139"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","position":2,"name":"1139","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/#listItem","name":"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/#listItem","position":3,"name":"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/","name":"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"Este fin de semana arrancan las actividades culturales con el acto de bienvenida a dos ni\u00f1os saharuis y el espect\u00e1culo \u2018El alquimista del sonido\u2019 Ciempozuelos inicia las actividades culturales programadas para este verano 2015 este s\u00e1bado, 4 de julio, a las 20.00 horas con el acto de bienvenida de dos ni\u00f1os saharauis que pasar\u00e1n las","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-06-29T10:47:07+02:00","dateModified":"2015-06-29T10:47:07+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"Este fin de semana arrancan las actividades culturales con el acto de bienvenida a dos ni\u00f1os saharuis y el espect\u00e1culo \u2018El alquimista del sonido\u2019 Ciempozuelos inicia las actividades culturales programadas para este verano 2015 este s\u00e1bado, 4 de julio, a las 20.00 horas con el acto de bienvenida de dos ni\u00f1os saharauis que pasar\u00e1n las","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/","article:published_time":"2015-06-29T10:47:07+00:00","article:modified_time":"2015-06-29T10:47:07+00:00","twitter:card":"summary","twitter:title":"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"Este fin de semana arrancan las actividades culturales con el acto de bienvenida a dos ni\u00f1os saharuis y el espect\u00e1culo \u2018El alquimista del sonido\u2019 Ciempozuelos inicia las actividades culturales programadas para este verano 2015 este s\u00e1bado, 4 de julio, a las 20.00 horas con el acto de bienvenida de dos ni\u00f1os saharauis que pasar\u00e1n las"},"aioseo_meta_data":{"post_id":"10065","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:08:06","updated":"2025-06-04 16:42:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/\" title=\"1139\">1139<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1139","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/"},{"label":"Vacaciones en paz y Fausto inauguran los Veranos Culturales 2015 de Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/29\/vacaciones-en-paz-y-fausto-inauguran-los-veranos-culturales-2015-de-ciempozuelos\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:57:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10065"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10065\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}