{"id":10045,"date":"2015-06-24T17:40:34","date_gmt":"2015-06-24T17:40:34","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/"},"modified":"2015-06-24T17:40:34","modified_gmt":"2015-06-24T17:40:34","slug":"la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/","title":{"rendered":"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: left;\"><em>El horario ser\u00e1 de 12.00 a 20.00 horas y permanecer\u00e1 abierta hasta el d\u00eda 10 de septiembre<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\"><span style=\"text-align: justify; font-size: 12.1599998474121px; line-height: 1.3em;\">Una vez terminados los trabajos de puesta a punto, a partir de este viernes, 26 de junio, y hasta el 10 de septiembre los vecinos y vecinas de Ciempozuelos podr\u00e1n disfrutar de la piscina de verano municipal en horario de 12.00 a 20.00 horas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em; text-align: justify;\">En cuanto a las tarifas de entrada, se adjunta la tabla con los precios para ni\u00f1os, adultos y jubilados y los abonos en sus distintas categor\u00edas. Tambi\u00e9n se puede consultar en este archivo la documentaci\u00f3n necesaria para adquirir el abono y los precios de los cursos de nataci\u00f3n.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Respecto a los precios, regulados por contrato, desde el Ayuntamiento se ha trabajado con la empresa adjudicataria para proceder a un descuento respecto en algunas tarifas y abonos de temporada de entre un 10 y 25%, sobre todo para familias numerosas. Tambi\u00e9n se establece un precio m\u00e1s asequible para los jubilados, igualando su tarifa a la de infantil.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">En cuanto a las familias en riesgo de exclusi\u00f3n social se est\u00e1 trabajando con los servicios sociales del Ayuntamiento para poder establecer una v\u00eda<\/span><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">que permita un descuento.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Estas tarifas se han negociado con el objetivo de adecuar los precios a las necesidades de los vecinos y vecinas de Ciempozuelos y en base a lo que, en un principio, estaba registrado en el contrato.<\/span><\/p>\n<p>Descargar archivo: {jd_file file==346}<\/p>\n<p>Descargar archivo: {jd_file file==347}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El horario ser\u00e1 de 12.00 a 20.00 horas y permanecer\u00e1 abierta hasta el d\u00eda 10 de septiembre Una vez terminados los trabajos de puesta a punto, a partir de este viernes, 26 de junio, y hasta el 10 de septiembre los vecinos y vecinas de Ciempozuelos podr\u00e1n disfrutar de la piscina de verano municipal en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1239],"class_list":["post-10045","post","type-post","status-publish","format-standard","hentry","tag-1239"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El horario ser\u00e1 de 12.00 a 20.00 horas y permanecer\u00e1 abierta hasta el d\u00eda 10 de septiembre Una vez terminados los trabajos de puesta a punto, a partir de este viernes, 26 de junio, y hasta el 10 de septiembre los vecinos y vecinas de Ciempozuelos podr\u00e1n disfrutar de la piscina de verano municipal en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El horario ser\u00e1 de 12.00 a 20.00 horas y permanecer\u00e1 abierta hasta el d\u00eda 10 de septiembre Una vez terminados los trabajos de puesta a punto, a partir de este viernes, 26 de junio, y hasta el 10 de septiembre los vecinos y vecinas de Ciempozuelos podr\u00e1n disfrutar de la piscina de verano municipal en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-06-24T17:40:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-06-24T17:40:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El horario ser\u00e1 de 12.00 a 20.00 horas y permanecer\u00e1 abierta hasta el d\u00eda 10 de septiembre Una vez terminados los trabajos de puesta a punto, a partir de este viernes, 26 de junio, y hasta el 10 de septiembre los vecinos y vecinas de Ciempozuelos podr\u00e1n disfrutar de la piscina de verano municipal en\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\\\/#blogposting\",\"name\":\"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes - Ayuntamiento de Ciempozuelos\",\"headline\":\"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-06-24T17:40:34+02:00\",\"dateModified\":\"2015-06-24T17:40:34+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\\\/#webpage\"},\"articleSection\":\"1086\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1086\\\/#listItem\",\"name\":\"1086\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1086\\\/#listItem\",\"position\":2,\"name\":\"1086\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1086\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\\\/#listItem\",\"name\":\"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\\\/#listItem\",\"position\":3,\"name\":\"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1086\\\/#listItem\",\"name\":\"1086\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\\\/\",\"name\":\"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes - Ayuntamiento de Ciempozuelos\",\"description\":\"El horario ser\\u00e1 de 12.00 a 20.00 horas y permanecer\\u00e1 abierta hasta el d\\u00eda 10 de septiembre Una vez terminados los trabajos de puesta a punto, a partir de este viernes, 26 de junio, y hasta el 10 de septiembre los vecinos y vecinas de Ciempozuelos podr\\u00e1n disfrutar de la piscina de verano municipal en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-06-24T17:40:34+02:00\",\"dateModified\":\"2015-06-24T17:40:34+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes - Ayuntamiento de Ciempozuelos","description":"El horario ser\u00e1 de 12.00 a 20.00 horas y permanecer\u00e1 abierta hasta el d\u00eda 10 de septiembre Una vez terminados los trabajos de puesta a punto, a partir de este viernes, 26 de junio, y hasta el 10 de septiembre los vecinos y vecinas de Ciempozuelos podr\u00e1n disfrutar de la piscina de verano municipal en","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/#blogposting","name":"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes - Ayuntamiento de Ciempozuelos","headline":"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-06-24T17:40:34+02:00","dateModified":"2015-06-24T17:40:34+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/#webpage"},"articleSection":"1086"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/#listItem","name":"1086"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/#listItem","position":2,"name":"1086","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/#listItem","name":"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/#listItem","position":3,"name":"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/#listItem","name":"1086"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/","name":"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes - Ayuntamiento de Ciempozuelos","description":"El horario ser\u00e1 de 12.00 a 20.00 horas y permanecer\u00e1 abierta hasta el d\u00eda 10 de septiembre Una vez terminados los trabajos de puesta a punto, a partir de este viernes, 26 de junio, y hasta el 10 de septiembre los vecinos y vecinas de Ciempozuelos podr\u00e1n disfrutar de la piscina de verano municipal en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-06-24T17:40:34+02:00","dateModified":"2015-06-24T17:40:34+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes - Ayuntamiento de Ciempozuelos","og:description":"El horario ser\u00e1 de 12.00 a 20.00 horas y permanecer\u00e1 abierta hasta el d\u00eda 10 de septiembre Una vez terminados los trabajos de puesta a punto, a partir de este viernes, 26 de junio, y hasta el 10 de septiembre los vecinos y vecinas de Ciempozuelos podr\u00e1n disfrutar de la piscina de verano municipal en","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/","article:published_time":"2015-06-24T17:40:34+00:00","article:modified_time":"2015-06-24T17:40:34+00:00","twitter:card":"summary","twitter:title":"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes - Ayuntamiento de Ciempozuelos","twitter:description":"El horario ser\u00e1 de 12.00 a 20.00 horas y permanecer\u00e1 abierta hasta el d\u00eda 10 de septiembre Una vez terminados los trabajos de puesta a punto, a partir de este viernes, 26 de junio, y hasta el 10 de septiembre los vecinos y vecinas de Ciempozuelos podr\u00e1n disfrutar de la piscina de verano municipal en"},"aioseo_meta_data":{"post_id":"10045","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:06:22","updated":"2025-06-04 16:40:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/\" title=\"1086\">1086<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa piscina municipal de Ciempozuelos inicia la temporada de verano este viernes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1086","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1086\/"},{"label":"La piscina municipal de Ciempozuelos inicia la temporada de verano este viernes","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/la-piscina-municipal-de-ciempozuelos-inicia-la-temporada-de-verano-este-viernes\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:51:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10045"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10045\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}