{"id":10031,"date":"2015-06-24T09:08:17","date_gmt":"2015-06-24T09:08:17","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/"},"modified":"2015-06-24T09:08:17","modified_gmt":"2015-06-24T09:08:17","slug":"vacaciones-en-paz-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/","title":{"rendered":"Vacaciones en paz"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: left;\"><em>Arrancan los veranos culturales con la fiesta de bienvenida de dos ni\u00f1os saharauis<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\"><span style=\"text-align: justify; font-size: 12.1599998474121px; line-height: 1.3em;\">El Ayuntamiento de Ciempozuelos comienza sus veranos culturales el s\u00e1bado d\u00eda 4 colaborando en una fiesta de bienvenida a Amin y Maroua, unos ni\u00f1os saharauis que vienen a pasar el verano a Ciempozuelos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Durante la jornada se realizar\u00e1 una batalla de globos de agua, juegos infantiles y sobre todo concienciaci\u00f3n sobre la situaci\u00f3n que vive la poblaci\u00f3n saharaui.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arrancan los veranos culturales con la fiesta de bienvenida de dos ni\u00f1os saharauis El Ayuntamiento de Ciempozuelos comienza sus veranos culturales el s\u00e1bado d\u00eda 4 colaborando en una fiesta de bienvenida a Amin y Maroua, unos ni\u00f1os saharauis que vienen a pasar el verano a Ciempozuelos. Durante la jornada se realizar\u00e1 una batalla de globos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1217],"class_list":["post-10031","post","type-post","status-publish","format-standard","hentry","tag-1217"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Arrancan los veranos culturales con la fiesta de bienvenida de dos ni\u00f1os saharauis El Ayuntamiento de Ciempozuelos comienza sus veranos culturales el s\u00e1bado d\u00eda 4 colaborando en una fiesta de bienvenida a Amin y Maroua, unos ni\u00f1os saharauis que vienen a pasar el verano a Ciempozuelos. Durante la jornada se realizar\u00e1 una batalla de globos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vacaciones en paz - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Arrancan los veranos culturales con la fiesta de bienvenida de dos ni\u00f1os saharauis El Ayuntamiento de Ciempozuelos comienza sus veranos culturales el s\u00e1bado d\u00eda 4 colaborando en una fiesta de bienvenida a Amin y Maroua, unos ni\u00f1os saharauis que vienen a pasar el verano a Ciempozuelos. Durante la jornada se realizar\u00e1 una batalla de globos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-06-24T09:08:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-06-24T09:08:17+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Vacaciones en paz - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Arrancan los veranos culturales con la fiesta de bienvenida de dos ni\u00f1os saharauis El Ayuntamiento de Ciempozuelos comienza sus veranos culturales el s\u00e1bado d\u00eda 4 colaborando en una fiesta de bienvenida a Amin y Maroua, unos ni\u00f1os saharauis que vienen a pasar el verano a Ciempozuelos. Durante la jornada se realizar\u00e1 una batalla de globos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/vacaciones-en-paz-3\\\/#blogposting\",\"name\":\"Vacaciones en paz - Ayuntamiento de Ciempozuelos\",\"headline\":\"Vacaciones en paz\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-06-24T09:08:17+02:00\",\"dateModified\":\"2015-06-24T09:08:17+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/vacaciones-en-paz-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/vacaciones-en-paz-3\\\/#webpage\"},\"articleSection\":\"1139\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/vacaciones-en-paz-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"position\":2,\"name\":\"1139\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/vacaciones-en-paz-3\\\/#listItem\",\"name\":\"Vacaciones en paz\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/vacaciones-en-paz-3\\\/#listItem\",\"position\":3,\"name\":\"Vacaciones en paz\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/vacaciones-en-paz-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/vacaciones-en-paz-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/vacaciones-en-paz-3\\\/\",\"name\":\"Vacaciones en paz - Ayuntamiento de Ciempozuelos\",\"description\":\"Arrancan los veranos culturales con la fiesta de bienvenida de dos ni\\u00f1os saharauis El Ayuntamiento de Ciempozuelos comienza sus veranos culturales el s\\u00e1bado d\\u00eda 4 colaborando en una fiesta de bienvenida a Amin y Maroua, unos ni\\u00f1os saharauis que vienen a pasar el verano a Ciempozuelos. Durante la jornada se realizar\\u00e1 una batalla de globos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/24\\\/vacaciones-en-paz-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-06-24T09:08:17+02:00\",\"dateModified\":\"2015-06-24T09:08:17+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Vacaciones en paz - Ayuntamiento de Ciempozuelos","description":"Arrancan los veranos culturales con la fiesta de bienvenida de dos ni\u00f1os saharauis El Ayuntamiento de Ciempozuelos comienza sus veranos culturales el s\u00e1bado d\u00eda 4 colaborando en una fiesta de bienvenida a Amin y Maroua, unos ni\u00f1os saharauis que vienen a pasar el verano a Ciempozuelos. Durante la jornada se realizar\u00e1 una batalla de globos","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/#blogposting","name":"Vacaciones en paz - Ayuntamiento de Ciempozuelos","headline":"Vacaciones en paz","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-06-24T09:08:17+02:00","dateModified":"2015-06-24T09:08:17+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/#webpage"},"articleSection":"1139"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","position":2,"name":"1139","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/#listItem","name":"Vacaciones en paz"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/#listItem","position":3,"name":"Vacaciones en paz","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/","name":"Vacaciones en paz - Ayuntamiento de Ciempozuelos","description":"Arrancan los veranos culturales con la fiesta de bienvenida de dos ni\u00f1os saharauis El Ayuntamiento de Ciempozuelos comienza sus veranos culturales el s\u00e1bado d\u00eda 4 colaborando en una fiesta de bienvenida a Amin y Maroua, unos ni\u00f1os saharauis que vienen a pasar el verano a Ciempozuelos. Durante la jornada se realizar\u00e1 una batalla de globos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-06-24T09:08:17+02:00","dateModified":"2015-06-24T09:08:17+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Vacaciones en paz - Ayuntamiento de Ciempozuelos","og:description":"Arrancan los veranos culturales con la fiesta de bienvenida de dos ni\u00f1os saharauis El Ayuntamiento de Ciempozuelos comienza sus veranos culturales el s\u00e1bado d\u00eda 4 colaborando en una fiesta de bienvenida a Amin y Maroua, unos ni\u00f1os saharauis que vienen a pasar el verano a Ciempozuelos. Durante la jornada se realizar\u00e1 una batalla de globos","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/","article:published_time":"2015-06-24T09:08:17+00:00","article:modified_time":"2015-06-24T09:08:17+00:00","twitter:card":"summary","twitter:title":"Vacaciones en paz - Ayuntamiento de Ciempozuelos","twitter:description":"Arrancan los veranos culturales con la fiesta de bienvenida de dos ni\u00f1os saharauis El Ayuntamiento de Ciempozuelos comienza sus veranos culturales el s\u00e1bado d\u00eda 4 colaborando en una fiesta de bienvenida a Amin y Maroua, unos ni\u00f1os saharauis que vienen a pasar el verano a Ciempozuelos. Durante la jornada se realizar\u00e1 una batalla de globos"},"aioseo_meta_data":{"post_id":"10031","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:05:04","updated":"2025-06-04 16:40:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/\" title=\"1139\">1139<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVacaciones en paz\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1139","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/"},{"label":"Vacaciones en paz","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/24\/vacaciones-en-paz-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:47:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10031"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10031\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}