{"id":2431,"date":"2019-02-27T12:07:35","date_gmt":"2019-02-27T12:07:35","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/?page_id=2431"},"modified":"2025-10-29T13:22:15","modified_gmt":"2025-10-29T12:22:15","slug":"historiadeciempozuelos","status":"publish","type":"page","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/","title":{"rendered":"Historia de Ciempozuelos"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: #020724;background-position: left top;background-repeat: no-repeat;padding-top:110px;padding-right:0px;padding-bottom:90px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-column-no-min-height\" style=\"margin-top:0px;margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:center center;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none fusion-no-small-visibility\"><img decoding=\"async\" width=\"300\" height=\"168\" title=\"CABECERA_LOGO_HISTORIA_blanco\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2021\/01\/CABECERA_LOGO_HISTORIA_blanco-300x168.png\" class=\"img-responsive wp-image-3836\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2021\/01\/CABECERA_LOGO_HISTORIA_blanco-200x112.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2021\/01\/CABECERA_LOGO_HISTORIA_blanco-400x224.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2021\/01\/CABECERA_LOGO_HISTORIA_blanco.png 594w\" sizes=\"(max-width: 800px) 100vw, 300px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-1\"><h2 style=\"text-align: center;\"><span style=\"color: #edecdc;\"><span style=\"caret-color: #ffffff;\">Una gran historia que contar.<\/span><\/span><\/h2>\n<p style=\"text-align: center; color: #edecdc;\">El origen de Ciempozuelos se remonta al a\u00f1o 180 a. C. bajo dominaci\u00f3n romana, cuando se estableci\u00f3 el primer n\u00facleo que se conoce. Los colonizadores ser\u00edan oriundos de la ciudad de Puzol y de las isla de Ischia, en el golfo de N\u00e1poles, y la localidad recibi\u00f3 el nombre de Ischadia -en griego &#8220;\u00c1ridos higuerales&#8221;- por la abundancia de este frutal en la zona.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container fusion-parallax-none nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-image: url(&quot;http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/CABECERA_HISTORIA_franja__ok_2.jpg&quot;);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-align-content-space-between fusion-flex-justify-content-center\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-center\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-center fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-1 content-boxes-icon-with-title content-left\" data-animationOffset=\"100%\" style=\"margin-top:20px;margin-bottom:20px;\"><style type=\"text\/css\">.fusion-content-boxes-1 .heading .content-box-heading {color:#333333;}\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-link-icon-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-link-icon-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .fusion-read-more:hover:after,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .fusion-read-more:hover:before,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .fusion-read-more:hover,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-link-icon-hover .icon .circle-no,\n\t\t\t\t\t.fusion-content-boxes-1 .heading .heading-link:hover .content-box-heading {\n\t\t\t\t\t\tcolor: #519c30;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box-hover .icon .circle-no {\n\t\t\t\t\t\tcolor: #519c30 !important;\n\t\t\t\t\t}.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button {background: #519c30;color: #ffffff;}.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button .fusion-button-text {color: #ffffff;}\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon > span {\n\t\t\t\t\t\tbackground-color: #519c30 !important;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box-hover .heading .icon > span {\n\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t}<\/style><div class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-fade\" style=\"background-color:rgba(255,255,255,0);\" data-animationOffset=\"100%\"><div class=\"heading icon-left\"><h2 class=\"content-box-heading\" style=\"font-size:18px;line-height:23px;\"><br \/>\n<\/h2><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\" style=\"color:#747474;\">\n<\/div><\/div><\/div><style type=\"text\/css\">\n\t\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .heading-link:hover .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box:hover .heading-link .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-1 .fusion-content-box-hover .link-area-box-hover .heading .icon i.circle-yes {\n\t\t\t\t\t\t\tbackground-color: #519c30 !important;\n\t\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t\t}<\/style><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-3 fusion-columns-total-1 fusion-content-boxes-2 content-boxes-icon-with-title content-left\" data-animationOffset=\"100%\" style=\"margin-top:20px;margin-bottom:20px;\"><style type=\"text\/css\">.fusion-content-boxes-2 .heading .content-box-heading {color:#333333;}\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-link-icon-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-link-icon-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .fusion-read-more:hover:after,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .fusion-read-more:hover:before,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .fusion-read-more:hover,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-link-icon-hover .icon .circle-no,\n\t\t\t\t\t.fusion-content-boxes-2 .heading .heading-link:hover .content-box-heading {\n\t\t\t\t\t\tcolor: #519c30;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box-hover .icon .circle-no {\n\t\t\t\t\t\tcolor: #519c30 !important;\n\t\t\t\t\t}.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button {background: #519c30;color: #ffffff;}.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button .fusion-button-text {color: #ffffff;}\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon > span {\n\t\t\t\t\t\tbackground-color: #519c30 !important;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box-hover .heading .icon > span {\n\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t}<\/style><div class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-4 col-md-4 col-sm-4 fusion-content-box-hover content-box-column-first-in-row content-box-column-last\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-fade\" style=\"background-color:rgba(255,255,255,0);\" data-animationOffset=\"100%\"><div class=\"heading icon-left\"><h2 class=\"content-box-heading\" style=\"font-size:18px;line-height:23px;\"><br \/>\n<\/h2><\/div><\/div><\/div><style type=\"text\/css\">\n\t\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .heading-link:hover .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box:hover .heading-link .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-2 .fusion-content-box-hover .link-area-box-hover .heading .icon i.circle-yes {\n\t\t\t\t\t\t\tbackground-color: #519c30 !important;\n\t\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t\t}<\/style><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-2{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 67px;margin-bottom : 22px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: #020724;background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;flex-grow:3;width:100%;\"><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-2{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-2 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-0 fusion-content-boxes-3 content-boxes-icon-with-title content-left\" data-animationOffset=\"100%\" style=\"margin-top:20px;margin-bottom:20px;\"><style type=\"text\/css\">.fusion-content-boxes-3 .heading .content-box-heading {color:#333333;}\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-link-icon-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-link-icon-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-box-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-box-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .fusion-read-more:hover:after,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .fusion-read-more:hover:before,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .fusion-read-more:hover,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-link-icon-hover .icon .circle-no,\n\t\t\t\t\t.fusion-content-boxes-3 .heading .heading-link:hover .content-box-heading {\n\t\t\t\t\t\tcolor: #519c30;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-box-hover .icon .circle-no {\n\t\t\t\t\t\tcolor: #519c30 !important;\n\t\t\t\t\t}.fusion-content-boxes-3 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button {background: #519c30;color: #ffffff;}.fusion-content-boxes-3 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button .fusion-button-text {color: #ffffff;}\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon > span {\n\t\t\t\t\t\tbackground-color: #519c30 !important;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-3 .fusion-content-box-hover .link-area-box-hover .heading .icon > span {\n\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t}<\/style><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_2 1_2 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-2\"><h2 class=\"fusion-responsive-typography-calculated\" style=\"color: #edecdc; --fontsize: 48; line-height: 1.19;\" data-fontsize=\"48\" data-lineheight=\"57px\">Or\u00edgenes del nombre de Ciempozuelos<\/h2>\n<p style=\"color: #edecdc;\">El nombre de Ciempozuelos no es casualidad. Su peculiar subsuelo est\u00e1 cargado de historia. Bajo las casas de la localidad brota abundante agua que, durante siglos, ha servido para el abastecimiento de los vecinos y para regar las cosechas.<br \/>\nA partir del siglo XIV, se comenzaron a construir galer\u00edas principales en el subsuelo del municipio, a las que cada vecino conectaba sus propias galer\u00edas desde sus viviendas para garantizarse la recogida de agua. Lo que gener\u00f3 una intrincada red de pasadizos kilom\u00e9tricos que cruzan el pueblo y que tienen aproximadamente 1,50 metros de ancho.<br \/>\nEstos canales tambi\u00e9n sirvieron para reconducir los manantiales hasta la Vega de Ciempozuelos, dando abastecimiento de agua a las cosechas.<\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-nested-column-0{width:50% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-nested-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 3.84%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 3.84%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-nested-column-0{width:100% !important;order : 0;}.fusion-builder-nested-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-nested-column-0{width:100% !important;order : 0;}.fusion-builder-nested-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_1_2 1_2 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:rgba(0,0,0,0);padding: 0px 0px 0px 0px;\"><div ><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"600\" title=\"Plaza de la Constituci\u00f3n\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Plaza-de-la-Constitucion.png\" class=\"img-responsive wp-image-26291\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Plaza-de-la-Constitucion-200x200.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Plaza-de-la-Constitucion-400x400.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Plaza-de-la-Constitucion.png 600w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-nested-column-1{width:50% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-nested-column-1 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 3.84%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 3.84%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-nested-column-1{width:100% !important;order : 0;}.fusion-builder-nested-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-nested-column-1{width:100% !important;order : 0;}.fusion-builder-nested-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-3{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-3 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-fullwidth.fusion-builder-row-3 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-view-cart):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link) , .fusion-fullwidth.fusion-builder-row-3 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-view-cart):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):before, .fusion-fullwidth.fusion-builder-row-3 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-view-cart):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):after {color: #020724;}.fusion-body .fusion-flex-container.fusion-builder-row-3{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-parallax-none nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: #ffefbf;background-image: url(&quot;https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/05\/Fondo-historia4.webp&quot;);background-position: center center;background-repeat: no-repeat;padding-top:90px;padding-right:0px;padding-bottom:57px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"margin-top:0px;margin-bottom:40px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:rgba(6,6,45,0);border-width: 0 0 4px 0;border-color:rgba(255,229,191,0);border-style:solid;box-shadow:0px 20px 21px -13px #000000;;padding: 60px 20px 0px 20px;\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-text fusion-text-3\" style=\"text-align:center;\"><h3><strong>CAR\u00c1CTERES GENERALES<\/strong><\/h3>\n<\/div><style type=\"text\/css\">#accordion-2431-1 .fusion-panel:hover, #accordion-2431-1 .fusion-panel.hover{ background-color: rgba(249,249,249,0.9) } #accordion-2431-1 .fusion-panel { border-color:#000005; border-width:1px; background-color:rgba(249,249,249,0.9); }.fusion-accordian  #accordion-2431-1 .panel-title a .fa-fusion-box{ color: #eaeaea;}.fusion-accordian  #accordion-2431-1 .panel-title a .fa-fusion-box:before{ font-size: 27px; width: 27px;}.fusion-accordian  #accordion-2431-1 .panel-title a{font-size:15px;}.fusion-accordian  #accordion-2431-1 .fa-fusion-box { background-color: #aa7803;border-color: #aa7803;}.fusion-accordian  #accordion-2431-1 .panel-title a:hover, #accordion-2431-1 .fusion-toggle-boxed-mode:hover .panel-title a { color: #0a0a0f;}.fusion-accordian  #accordion-2431-1 .panel-title .active .fa-fusion-box,.fusion-accordian  #accordion-2431-1 .panel-title a:hover .fa-fusion-box { background-color: #0a0a0f!important;border-color: #0a0a0f!important;}<\/style><div class=\"accordian fusion-accordian\"><div class=\"panel-group\" id=\"accordion-2431-1\" role=\"tablist\"><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a class=\"active\" aria-expanded=\"true\" aria-selected=\"true\" aria-controls=\"2b33a6d5c407ea826\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-1\" data-target=\"#2b33a6d5c407ea826\" href=\"#2b33a6d5c407ea826\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">CAR\u00c1CTERES GENERALES I<\/span><\/a><\/h4><\/div><div id=\"2b33a6d5c407ea826\" class=\"panel-collapse collapse in\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p style=\"font-weight: 400;\">El t\u00e9rmino municipal de Ciempozuelos est\u00e1 situado en el sur de la Comunidad de Madrid y tiene una extensi\u00f3n de 49,60 km2. Pertenece a la denominada Sagra madrile\u00f1a, cuyo l\u00edmite geogr\u00e1fico es el r\u00edo Jarama, y linda al norte con San Mart\u00edn de la Vega y Valdemoro, al este con Titulcia y Chinch\u00f3n, al sur con Aranjuez y Sese\u00f1a (Toledo) y al oeste de nuevo con Valdemoro.<\/p>\n<p>El paisaje, como es habitual en La Sagra, nos ofrece una topograf\u00eda llana, con peque\u00f1as colinas entre las dos zonas en que se divide el territorio: la vega del Jarama en la mitad oriental y la meseta en la occidental. Los cerros m\u00e1s importantes son Butarr\u00f3n (656 m.) en el extremo nordeste y La Pe\u00f1uela, Palomero y Lega\u00f1a al sur.<\/p>\n<p>Respecto a la hidrograf\u00eda, el cauce m\u00e1s rese\u00f1able lo constituye el mencionado r\u00edo Jarama, que, en buena parte de su curso, define el l\u00edmite este de Ciempozuelos y forma una vega de gran valor ambiental. Sus dos afluentes -de escaso caudal- son los arroyos Palomero, en el \u00e1rea central del territorio municipal, y del Valle Grande, en el sur y procedente del t\u00e9rmino de Sese\u00f1a. Adem\u00e1s, el canal del Jarama discurre paralelo y alternante al r\u00edo hasta desembocar en el Tajo, regando con sus m\u00faltiples derivaciones -acequias de la Media Luna, de Matalobos (que sirve de lindero con San Mart\u00edn de la Vega), de Serrano; caceras de la Huesa, de las Moreras, etc&#8230;- m\u00e1s de 2.000 ha. de vega. La vegetaci\u00f3n dominante en la vega es la propia de los valles fluviales: especies como pl\u00e1tanos, olmos, chopos, \u00e1lamos, casta\u00f1os de Indias, tilos o tarayes crean espacios naturales de gran belleza y valor ecol\u00f3gico enclavados en el denominado Parque Regional del Sureste (ejemplos son los sotos Guti\u00e9rrez, de la Chopera, del Parral y de las Arriadas). En la meseta, sin embargo, el panorama es muy diferente: la estepa salina, en la que son abundantes el cardo, el sisallo rojo y las compuestas, queda envuelta por el esparto o las gram\u00edneas, hasta llegar a \u00e1reas de matorral donde predominan las labiadas arom\u00e1ticas. Adem\u00e1s, la aparici\u00f3n de terrenos yes\u00edferos da lugar a eriales en los que la \u00fanica explotaci\u00f3n posible vuelve a ser el esparto, de manera que m\u00e1s de 1.400 ha. del territorio son pr\u00e1cticamente yermas o no aptas para el cultivo.<\/p>\n<p style=\"font-weight: 400;\">Las v\u00edas de comunicaci\u00f3n m\u00e1s importantes son la autov\u00eda A-4 (Madrid-C\u00e1diz) que discurre por el oeste del t\u00e9rmino municipal a lo largo de tan s\u00f3lo un par de kil\u00f3metros; la M-404, que tiene su intersecci\u00f3n con la autov\u00eda en el p.k. 30 de \u00e9sta y tras rodear el casco urbano de Ciempozuelos se dirige en direcci\u00f3n NO-SE hacia Chinch\u00f3n, y la M-307, cuyo trazado, en parte paralelo a la v\u00eda f\u00e9rrea Madrid-Alicante, nos conduce por el norte a San Mart\u00edn de la Vega y por el sur a la A-4. Como es habitual en los n\u00facleos rurales de car\u00e1cter agr\u00edcola, existe tambi\u00e9n una tupida red de caminos vecinales, empleados para acceder a las fincas de cultivo y, en el pasado, para comunicar el pueblo con los lugares colindantes. Entre \u00e9stos podemos destacar el camino de Postas, que alcanzaba la carretera general, hoy autov\u00eda, en el Km. 32, y el de Ciempozuelos, que lo hac\u00eda en el Km. 27, utilizados en los viajes a Toledo y Madrid respectivamente; adem\u00e1s, las -en su tiempo- importantes Salinas de Espartinas, al sur del municipio, contaban con un camino particular que las un\u00eda a la carretera general en el Km. 31. Otros caminos destacables son los del Molino del Rey, de Entrevi\u00f1as, del Soto Guti\u00e9rrez y del Portillo de los Guijos por el norte; de San Ant\u00f3n, del Soto de la Chopera, Hondo del Soto del Parral y del Soto de las Arriadas por el este; del Boquete Charra, de las Chozas, de las Carretas, de las Moreras, de la Cuesta Alta, Alto de Palomero, de los Corrales de Pach\u00f3n y de Matagallegos por el sur, y de la Asomadilla, de la Oliva, de Vaciasilos, de los Cestos y de Borrebruno por el oeste.<\/p>\n<p style=\"font-weight: 400;\">La ya mencionada v\u00eda f\u00e9rrea Madrid-Alicante discurre, en principio, por el lindero de Valdemoro, para posteriormente variar su rumbo en direcci\u00f3n norte-sur, separando la vega del Jarama de los terrenos de secano. El n\u00facleo urbano dispone de estaci\u00f3n en la l\u00ednea de Cercan\u00edas C-3 (Atocha-Aranjuez), por lo que las comunicaciones con la capital, de la cual dista 34 Km. por ferrocarril, son excelentes.<\/p>\n<p style=\"font-weight: 400;\">La densa trama de v\u00edas pecuarias tiene en los cordeles de las Merinas o de Palomero, de los Manchegos y de las C\u00e1rceles sus m\u00e1s notables representantes. El primero nace de una encrucijada o nudo viario constituido por el propio cordel, la Vereda Larga de los Cerros o de G\u00f3zquez y la Vereda de Sacejo o de la Huerta, en la llamada falda del Cerro Castillejo, enclave que sirve de l\u00edmite con el t\u00e9rmino de Valdemoro. Desde aqu\u00ed, y tras atravesar el puente del ferrocarril Madrid-Alicante, cruza el casco urbano de Ciempozuelos por el Barrio de las Cuevas del Prado hasta llegar al arroyo de Palomero, donde se encuentra el descansadero-abrevadero hom\u00f3nimo. A partir de este momento bordea los cerros que definen el tr\u00e1nsito a la vega del Jarama y, ya en direcci\u00f3n este-oeste, atraviesa la autov\u00eda A-4 penetrando en el t\u00e9rmino de Sese\u00f1a.<\/p>\n<p style=\"font-weight: 400;\">El Cordel de los Manchegos, procedente de San Mart\u00edn de la Vega, entra en Ciempozuelos cruzando la acequia de Matalobos y toma rumbo norte-sur discurriendo entre caceras y caminos que nos llevan a los cercanos sotos Guti\u00e9rrez, de la Chopera y del Parral. Llega finalmente a la dehesa o soto de las Arriadas y atraviesa el r\u00edo Jarama por el vado de Bayona para, ya en la jurisdicci\u00f3n de Titulcia, enlazar con la Ca\u00f1ada Real Galiana.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"f9d1ddb32b50a6cf6\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-1\" data-target=\"#f9d1ddb32b50a6cf6\" href=\"#f9d1ddb32b50a6cf6\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">CAR\u00c1CTERES GENERALES II<\/span><\/a><\/h4><\/div><div id=\"f9d1ddb32b50a6cf6\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>El Cordel de las C\u00e1rceles, por su parte, arranca del Cordel de las Merinas o de Palomero, atravesando el arroyo del mismo nombre hasta que, en los chozos de Cuesta Vieja, se ensancha sirviendo de descansadero de ganado. Contin\u00faa en direcci\u00f3n este-oeste y cruza sucesivamente la v\u00eda f\u00e9rrea Madrid-Alicante, la cacera de Serrano, la carretera de San Mart\u00edn de la Vega y las acequias del Jarama y de la Media Luna. Tras llegar a la finca El Sotillo, finaliza su recorrido en el r\u00edo Jarama, colindante ya con el t\u00e9rmino municipal de Titulcia.<\/p>\n<p>Adem\u00e1s de estos tres cordeles, hay otras seis veredas que completan la red de v\u00edas pecuarias. La Vereda de Sacejo o de la Huerta comienza en el ya citado nudo viario situado a los pies del Cerro Castillejo y sigue su curso por el trazado del antiguo ferrocarril de La Poveda en direcci\u00f3n oeste-este. Tras atravesar la acequia del Jarama cruza el Cordel de los Manchegos en el soto de Las Arriadas para finalizar en el r\u00edo Jarama. La Vereda de la Casa del Conde nace del Cordel de las Merinas o de Palomero, en el sur del t\u00e9rmino; toma rumbo NO-SE hacia las Salinas de Espartinas para cruzar la Carretera M-307, la v\u00eda f\u00e9rrea Madrid-Alicante y la acequia del Jarama y, tras servir de linde con Sese\u00f1a atravesando la finca Casa del Conde, termina, como la anterior, en el Jarama. La Vereda de Pe\u00f1alba o del Parral, de corto recorrido, tiene su inicio en el Cordel de los Manchegos y, con direcci\u00f3n O-E, atraviesa el soto de la Chopera hasta el r\u00edo Jarama a la altura de la isla de Pe\u00f1alba, donde existe un descansadero-abrevadero de ganados. La Vereda Larga de los Cerros o de G\u00f3zquez tambi\u00e9n parte de la falda del Cerro Castillejo, sirve de l\u00edmite con el t\u00e9rmino de Valdemoro y contin\u00faa por el norte en San Mart\u00edn de la Vega. Las dos \u00faltimas v\u00edas presentes en el t\u00e9rmino son la Vereda del Soto de Valdemoro al Puente de Palo, que procedente de Valdemoro atraviesa sucesivamente la Vereda Larga de los Cerros, la carretera de San Mart\u00edn de la Vega, la acequia del Jarama y el Cordel de los Manchegos, siempre en direcci\u00f3n O-E, hasta llegar al soto Guti\u00e9rrez y finalizar en el r\u00edo Jarama, y la Vereda del Cacer\u00f3n de Matalobos, al norte del t\u00e9rmino, que desde el camino de Entrevi\u00f1as delimita el lindero con San Mart\u00edn de la Vega al discurrir paralela a la citada acequia, cruza el Cordel de los Manchegos y termina tambi\u00e9n en el Jarama.<\/p>\n<p>El n\u00facleo de Ciempozuelos se encuentra situado en una suave ladera al borde del valle del Jarama, frente al Cerro Castillejo, y su caser\u00edo se extiende b\u00e1sicamente en las direcciones sur y oeste. Dos son las infraestructuras que han acotado su crecimiento: por una parte la Carretera M-404, que anteriormente cruzaba el pueblo y ahora lo bordea por el norte y este, y por otra la v\u00eda f\u00e9rrea Madrid-Alicante, aut\u00e9ntico borde urbano que discurre tambi\u00e9n por el l\u00edmite oriental del casco impidiendo, junto a las cercanas terrazas del valle, el desarrollo de esta zona.<\/p>\n<p>Respecto al origen del top\u00f3nimo, todas las fuentes consultadas son un\u00e1nimes: en el paraje conocido como Buzanca, a unos 2 Km. del n\u00facleo, comenzaba un canal que, en el pasado, surt\u00eda de agua a la fuente de la plaza del pueblo; como el manantial no era abundante se construyeron numerosos pozos que proporcionaron, adem\u00e1s del suficiente caudal, el nombre a la localidad.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"margin-top:0px;margin-bottom:40px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:rgba(6,6,45,0);border-width: 0 0 4px 0;border-color:rgba(255,229,191,0);border-style:solid;box-shadow:0px 20px 21px -13px #000000;;padding: 60px 20px 0px 20px;\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-text fusion-text-4\" style=\"text-align:center;\"><h3><strong>OR\u00cdGENES EN LA EDAD MEDIA<\/strong><\/h3>\n<\/div><style type=\"text\/css\">#accordion-2431-2 .fusion-panel:hover, #accordion-2431-2 .fusion-panel.hover{ background-color: rgba(249,249,249,0.9) } #accordion-2431-2 .fusion-panel { border-color:#000005; border-width:1px; background-color:rgba(249,249,249,0.9); }.fusion-accordian  #accordion-2431-2 .panel-title a .fa-fusion-box{ color: #eaeaea;}.fusion-accordian  #accordion-2431-2 .panel-title a .fa-fusion-box:before{ font-size: 27px; width: 27px;}.fusion-accordian  #accordion-2431-2 .panel-title a{font-size:15px;}.fusion-accordian  #accordion-2431-2 .fa-fusion-box { background-color: #aa7803;border-color: #aa7803;}.fusion-accordian  #accordion-2431-2 .panel-title a:hover, #accordion-2431-2 .fusion-toggle-boxed-mode:hover .panel-title a { color: #0a0a0f;}.fusion-accordian  #accordion-2431-2 .panel-title .active .fa-fusion-box,.fusion-accordian  #accordion-2431-2 .panel-title a:hover .fa-fusion-box { background-color: #0a0a0f!important;border-color: #0a0a0f!important;}<\/style><div class=\"accordian fusion-accordian\"><div class=\"panel-group\" id=\"accordion-2431-2\" role=\"tablist\"><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"86e52a465548eccda\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-2\" data-target=\"#86e52a465548eccda\" href=\"#86e52a465548eccda\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">OR\u00cdGENES EN LA EDAD MEDIA I<\/span><\/a><\/h4><\/div><div id=\"86e52a465548eccda\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<div class=\"page-header\">\n<p>Los abundantes restos de industria l\u00edtica achelense hallados en los valles de los r\u00edos madrile\u00f1os -Tajo, Henares, Jarama, Manzanares- confirman la presencia de poblaci\u00f3n n\u00f3mada en nuestra Comunidad desde unos trescientos mil a\u00f1os. En el caso particular de Ciempozuelos, y avanzando ya hasta la Edad del Bronce, en 1894 se encontraron restos humanos y vasijas, procedentes de una necr\u00f3polis, al efectuar obras de terraplenado en la actual Carretera M-307, frente al Cerro Castillejo. Las cinco tumbas existentes -todas excavadas en tierra, excepto una tallada en piedra- no permiten asociar el enterramiento a un n\u00facleo concreto de habitaci\u00f3n, pero la cer\u00e1mica, que formaba parte del ajuar funerario, presenta unas caracter\u00edsticas que la hacen especialmente singular: se trata de vasos, cazuelas y cuencos realizados en arcilla negra o roja, pulimentados con una capa de barro m\u00e1s fino, que se decoran con t\u00e9cnica incisa dibujando motivos geom\u00e9tricos rellenos de pasta blanca. El conjunto ha dado nombre a un tipo especial de cer\u00e1mica -el vaso campaniforme de Ciempozuelos- fechable en el Bronce Inicial, entre 1970 y 1470 a.C., y presente en otros yacimientos madrile\u00f1os. Adem\u00e1s, completando el ajuar, se encontraron punzones de secci\u00f3n cuadrada y puntas de flecha de cobre. Tambi\u00e9n pertenecen a la Edad de Bronce los restos de industria l\u00edtica -sobre todo hojas de cuchillo- y cer\u00e1mica muy basta localizados en el paraje del llamado La Palomera, al sur del territorio y junto al cerro del mismo nombre. Como el territorio ha sido un poco prospectado, todo hace pensar que un estudio arqueol\u00f3gico m\u00e1s completo sacar\u00eda a la luz un gran n\u00famero de yacimientos, seguramente de gran inter\u00e9s, puesto que actualmente est\u00e1n representados en el t\u00e9rmino municipal desde la Edad del Bronce hasta el Medievo. Respecto al primer n\u00facleo m\u00e1s o menos estable de poblaci\u00f3n, algunas fuentes apuntan a la posible fundaci\u00f3n de Ciempozuelos en el a\u00f1o 180 a.C., ya bajo la dominaci\u00f3n romana. Los colonizadores ser\u00edan oriundos de la ciudad de Puzol y de la isla de Ischia, en el golfo de N\u00e1poles, y la localidad recibi\u00f3 el nombre de Ischadia -en griego \u201c\u00e1ridos higuerales\u201d- por la abundancia de este frutal en la zona.<\/p>\n<p>En cualquier caso, son abundantes los restos romanos en toda la comarca y en el t\u00e9rmino de Ciempozuelos hay dos yacimientos inventariados: el llamado Cerro de las Tejas o Vedado de las Monjas y el monumento encontrado en el r\u00edo Jarama. El primero se halla en el SE del territorio, junto a la Vereda de las C\u00e1rceles, y en \u00e9l se encontraron cer\u00e1mica -terra sigillata, pintada y com\u00fan-, resto de m\u00e1rmol, un fuste y una basa de granito, y un sarc\u00f3fago del mismo material, pertenecientes a un posible tell muy aplanado por los cultivos.<\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"eddabba6e092f2d7b\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-2\" data-target=\"#eddabba6e092f2d7b\" href=\"#eddabba6e092f2d7b\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">OR\u00cdGENES EN LA EDAD MEDIA II<\/span><\/a><\/h4><\/div><div id=\"eddabba6e092f2d7b\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>En cuanto al monumento romano -incoado BIC (Bien de Inter\u00e9s Cultural) por resoluci\u00f3n de 8-7-1987 (BOE 9-9-87)-, los 33 sillares de piedra caliza extra\u00eddos del Jarama pertenecen a un gran edificio del que no se conocen su funci\u00f3n ni las caracter\u00edsticas exactas (podr\u00eda ser un arco triunfal), pero que, por las fechas en las que es datable -entre finales del siglo I y mediados del II d.C.-, constituye el resto m\u00e1s antiguo de la romanizaci\u00f3n en la Comunidad de Madrid. Las piezas rescatadas son 3 sillares de moldura decorada (uno de esquina), 4 de un friso liso con inscripci\u00f3n incompleta, 1 de cornisa denticular, 4 dovelas cuya curvatura permite deducir que el arco o arcos que formaban ten\u00eda un di\u00e1metro de 2,40 m., 2 salmeres, 1 moldura de imposta, 6 sillares con forma para asiento de dovelas y otros 12 restantes, quiz\u00e1s alguno de \u00e1tico. La inscripci\u00f3n del friso, en letra capital cuadrada, reza:<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/origenes3.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>SEX * PRISCO* FILIO (&#8230;)<br \/>\nF QVIR SEVERVS NEPO (&#8230;)<br \/>\n(ecerunt o posuerunt?) EIDEM (Q)<br \/>\nVE DEDICARVNT<\/p>\n<p>y por sus dimensiones se puede deducir que completo ocupar\u00eda un frente de unos 9 metros. En ella, dos personajes, abuelo y padre, de los que s\u00f3lo se conoce el \u201ccognomen\u201d del segundo, Severo, y su pertenencia a la tribu Quirina, dedican el monumento a Sexto Prisco, nieto e hijo de ambos. Tras la ca\u00edda del reino visigodo.<\/p>\n<p>-algunas fuentes especifican que nuestro pueblo fue cercado y destruido por los \u00e1rabes en el a\u00f1o 714-, ser\u00e1 Alfonso VI qui\u00e9n, una vez conquistado Toledo en 1085, repueble la zona, y entre otras localidades, Ciempozuelos. Un siglo despu\u00e9s, en documento fechado el 25 de marzo de 1190, Alfonso VIII cede a la Comunidad de Ciudad y Tierra de Segovia un total de 19 aldeas -el futuro sexmo de Valdemoro- enclavadas entre los r\u00edos Taju\u00f1a y Henares; entre ellas no est\u00e1 Ciempozuelos, puesto que, al parecer, era segoviana desde hace tiempo atr\u00e1s. En cualquier caso, lo cierto es que pas\u00f3 a formar parte del citado sexmo, uno de los trece que constitu\u00edan la Comunidad de Segovia y que se caracterizaba por formar un coto continuo, pero aislado geogr\u00e1ficamente del resto del territorio segoviano.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"2b2fc098e51ec523b\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-2\" data-target=\"#2b2fc098e51ec523b\" href=\"#2b2fc098e51ec523b\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">OR\u00cdGENES EN LA EDAD MEDIA III<\/span><\/a><\/h4><\/div><div id=\"2b2fc098e51ec523b\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>La pol\u00edtica expansionista de los segovianos hizo que las desavenencias con el concejo madrile\u00f1o acerca de los l\u00edmites jurisdiccionales de los sexmos fuesen frecuentes. Prueba de ello es el privilegio de amojonamiento, fechado en San Esteban de Gormaz el 29 de junio de 1239, en el que Fernando III define los l\u00edmites del sexmo de Valdemoro mediante 42 mojones que separaban Palomero, Pozuelo, Pinto, Covanobles, Torre de Aventresp\u00edn y Cuelgamuros -aldeas de Madrid-, de Sese\u00f1a, Espartinas, Valdemoro, G\u00f3zquez, Santisteban y Albende, pertenecientes a Segovia.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/origenes4.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>Espartinas, tambi\u00e9n llamado San Juan de las Salinas de Espartinas, y situado a unos 4 Km. al sur de Ciempozuelos, junto a la Carretera M-307, era, pues, uno de los enclaves medievales del sexmo, que dentro del actual t\u00e9rmino municipal pose\u00eda otras dos aldeas tambi\u00e9n desaparecidas: el Casar de San Ant\u00f3n, en el NE y de origen tardomedieval, y el Soto Guti\u00e9rrez, que bien pudiera ser una alquer\u00eda de la misma \u00e9poca o incluso de la Edad Moderna y se localiza en el mismo v\u00e9rtice nororiental, pero m\u00e1s cercano al r\u00edo Jarama. Espartinas, El Casar y Ciempozuelos-Las Chozas (el primero denominado \u201cSiete Pozuelos\u201d, derivado del lat\u00edn \u201csedes, sieds\u201d, lugar, asiento) eran, adem\u00e1s, tres de las cuadrillas en que se dividi\u00f3 la vega del Jarama, seg\u00fan consta en el Ordenamiento de 1302 que pretendi\u00f3, sin mucho \u00e9xito, fortalecer la repoblaci\u00f3n de la Transierra. Quiz\u00e1s por esta raz\u00f3n no volveremos a tener referencias de nuestro pueblo hasta 1427, fecha en la que el Arzobispado de Toledo ordena la inspecci\u00f3n de todas las iglesias del Arcedianato de Madrid. El visitador menciona los templos de Siete Pozuelos y El Casar e indica al respecto: \u201cestas iglesias son yermas, sin parroquianos, ni ornamentos, ni cl\u00e9rigo presente\u201d, dato que demuestra claramente que las citadas localidades estaban deshabitadas en dicha \u00e9poca. Por ello, a\u00f1os m\u00e1s tarde, reinando todav\u00eda Juan II, Segovia va a solicitar de nuevo autorizaci\u00f3n para repoblar las aldeas de su partido.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/origenes5.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>El privilegio, concedido por el monarca en Bayona (hoy Titulcia) en 1442 y confirmado por Enrique IV en Valladolid en 1457, implicaba a un vecino de la ciudad de Segovia, Don Juan Fern\u00e1ndez de Pi\u00f1a, que se compromet\u00eda a repoblar Ciempozuelos y otras tres localidades de la ribera del Jarama -San Mart\u00edn de la Vega, Vallequillas y El Casar- con 150 vecinos en cada una de ellas en un plazo de dos a\u00f1os. Los nuevos habitantes eran originarios de la Tierra de Segovia -en Ciempozuelos se instal\u00f3 el propio Pi\u00f1a- y, aunque las dos \u00faltimas aldeas se despoblaron pronto y los conflictos jurisdiccionales con Valdemoro fueron frecuentes (este concejo vio reducido notablemente su t\u00e9rmino), nuestro pueblo qued\u00f3 de nuevo fundado en su actual asentamiento. Entre las actividades econ\u00f3micas -b\u00e1sicamente agricultura y ganader\u00eda- destacaba ya la explotaci\u00f3n de las Salinas de Espartinas, propiedad real acerca de la cual existen numerosas provisiones dictadas durante el reinado de los Reyes Cat\u00f3licos, Juana I y Carlos I que regulaban su aprovechamiento.<\/p>\n<p>Unos a\u00f1os m\u00e1s tarde de la repoblaci\u00f3n de Ciempozuelos, en 1480, se va a producir un hecho de gran trascendencia para la historia local: los Reyes Cat\u00f3licos, con el fin de premiar la fidelidad de sus s\u00fabditos m\u00e1s leales, conceden el Se\u00f1or\u00edo de Chinch\u00f3n a los marqueses de Moya, Don Andr\u00e9s Cabrera y D\u00f1a. Beatriz de Bobadilla, y para ello segregaron de Segovia 1.200 vasallos incluidos en la totalidad del sexmo de Valdemoro y parte del de Casarrubios. Ciempozuelos pas\u00f3 a ser villa exenta, con propia y ordinaria jurisdicci\u00f3n, pero perteneciente al mayorazgo que poco despu\u00e9s, en 1496, fundan los Moya vincul\u00e1ndolo a su tercer hijo, Fernando Cabrera Bobadilla. \u00c9ste fue nombrado Conde de Chinch\u00f3n por Carlos I en 1520 y, a pesar del pleito interpuesto por el Concejo de Segovia que no se solucion\u00f3 hasta 1592, los dominios objeto de litigio -entre ellos nuestra localidad- quedaron bajo su propiedad, mediante el pago a los segovianos de una serie de compensaciones.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"margin-top:0px;margin-bottom:40px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:rgba(6,6,45,0);border-width: 0 0 4px 0;border-color:rgba(255,229,191,0);border-style:solid;box-shadow:0px 20px 21px -13px #000000;;padding: 60px 20px 0px 20px;\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-text fusion-text-5\" style=\"text-align:center;\"><h3><strong>SIGLOS XVI, XVII y XVIII<\/strong><\/h3>\n<\/div><style type=\"text\/css\">#accordion-2431-3 .fusion-panel:hover, #accordion-2431-3 .fusion-panel.hover{ background-color: rgba(249,249,249,0.9) } #accordion-2431-3 .fusion-panel { border-color:#000005; border-width:1px; background-color:rgba(249,249,249,0.9); }.fusion-accordian  #accordion-2431-3 .panel-title a .fa-fusion-box{ color: #eaeaea;}.fusion-accordian  #accordion-2431-3 .panel-title a .fa-fusion-box:before{ font-size: 27px; width: 27px;}.fusion-accordian  #accordion-2431-3 .panel-title a{font-size:15px;}.fusion-accordian  #accordion-2431-3 .fa-fusion-box { background-color: #aa7803;border-color: #aa7803;}.fusion-accordian  #accordion-2431-3 .panel-title a:hover, #accordion-2431-3 .fusion-toggle-boxed-mode:hover .panel-title a { color: #0a0a0f;}.fusion-accordian  #accordion-2431-3 .panel-title .active .fa-fusion-box,.fusion-accordian  #accordion-2431-3 .panel-title a:hover .fa-fusion-box { background-color: #0a0a0f!important;border-color: #0a0a0f!important;}<\/style><div class=\"accordian fusion-accordian\"><div class=\"panel-group\" id=\"accordion-2431-3\" role=\"tablist\"><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"7aa5fe1bb7ea8f979\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-3\" data-target=\"#7aa5fe1bb7ea8f979\" href=\"#7aa5fe1bb7ea8f979\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XVI, XVII y XVIII - I<\/span><\/a><\/h4><\/div><div id=\"7aa5fe1bb7ea8f979\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p>No son muchos los datos existentes sobre Ciempozuelos durante los siglos XVI y XVII, por lo que tendremos que esperar hasta la aparici\u00f3n de los censos y catastros de la Ilustraci\u00f3n para tener una visi\u00f3n m\u00e1s completa de la realidad del municipio. La estructura urbana era la habitual en los poblados agr\u00edcolas, configur\u00e1ndose inicialmente el n\u00facleo a lo largo de dos caminos: uno principal de Navalcarnero a Titulcia, que, en direcci\u00f3n NO-SE, discurr\u00eda por el actual trazado de las calles Jer\u00f3nimo del Moral, Pilar y Pe\u00f1uelas, y otro secundario con orientaci\u00f3n N-S, que coincide con la calle Reina Victoria. Entre esta \u00faltima v\u00eda, Jer\u00f3nimo del Moral y, como l\u00edmite sur, el eje definido por las calles Doctor Rivas-Capit\u00e1n de Oro Pulido (antiguo Camino de Chich\u00f3n) se extendi\u00f3 el caser\u00edo, celebr\u00e1ndose los primeros mercados en un amplio espacio libre, sin acotar y exterior al casco urbano, emplazado en lo que hoy en d\u00eda es la plaza Mayor.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos1.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>El posterior crecimiento, ya bajo el se\u00f1or\u00edo de los Condes de Chich\u00f3n, se realiz\u00f3 hacia el mediod\u00eda, llegando las nuevas manzanas hasta la calle de la Virgen, que conduc\u00eda por el este al camino de Cantarranas, de manera que se form\u00f3 un tejido urbano m\u00e1s o menos compacto, pero irregular y algo tortuoso, en el que el \u00fanico vac\u00edo lo constitu\u00edan la ya citada plaza Mayor y su continuaci\u00f3n por el SE en las actuales plaza de Ventura Rodr\u00edguez y parque del Pilar. En la primera mitad del siglo XVI se construy\u00f3 la manzana sur de la plaza Mayor, regulariz\u00e1ndose as\u00ed su traza, y a\u00f1os despu\u00e9s qued\u00f3 delimitado el espacio restante al levantarse la iglesia parroquial de Santa Mar\u00eda Magdalena con su cementerio contiguo, que ocupaba el parque del Pilar. De esta forma se configuraron las dos plazas que articulan el casco urbano de Ciempozuelos: la Mayor o de la Constituci\u00f3n, muy irregular y llamada inicialmente plaza de la Iglesia.<\/p>\n<p>El pueblo, por otra parte, gozaba de una situaci\u00f3n geogr\u00e1fica estrat\u00e9gica y en el Repertorio de Caminos de Juan de Villuga, de 1546, aparece citado como parte de dos itinerarios diferentes: uno que conduc\u00eda de Valencia a Salamanca -para ello se separaba de la actual Carretera en Fuentidue\u00f1a de Tajo tomando rumbo a Chinch\u00f3n, Titulcia, Ciempozuelos, Valdemoro, etc.-, y otro que desde Toledo llegaba a Alcal\u00e1 de Henares, pasando por Borox, Sese\u00f1a, el propio Ciempozuelos, San Mart\u00edn de la Vega y Loeches.<\/p>\n<p>Un acontecimiento hist\u00f3rico de cierta relevancia para la localidad fue la Revoluci\u00f3n Comunera de 1520, durante la cual los vecinos se sublevaron contra el conde de Chinch\u00f3n, siendo reducidos por D. Juan Arias D\u00e1vila, se\u00f1or de Torrej\u00f3n de Velasco y primer conde de Pu\u00f1onrostro. Como los da\u00f1os producidos en los castillos de Chich\u00f3n y Od\u00f3n, propiedad del conde, fueron cuantiosos, Ciempozuelos se vio obligado a pagar una fuerte multa de 500.000 maraved\u00edes.<\/p>\n<p>A\u00f1os m\u00e1s tarde, reinando ya Felipe II, se van a iniciar los primeros estudios sobre el posible trazado de un canal o acequia que, partiendo del Jarama, permitiese el riego de las tierras situadas en la vega, facilitando de esta manera un r\u00e1pido desarrollo econ\u00f3mico de la regi\u00f3n. Personajes tan relevantes en la \u00e9poca como Juanelo Turriano emitieron informes acerca de la viabilidad de la empresa, aunque tendremos que esperar a la publicaci\u00f3n de una Real C\u00e9dula de 22 de julio de 1578 para conocer que el plan s\u00f3lo contemplaba la construcci\u00f3n de un peque\u00f1o canal de unos 2,5 Km. en el que, seg\u00fan aventuran algunas fuentes, particip\u00f3 Juan de Herrera dise\u00f1ando las primeras presas de toma. Sin embargo, y a pesar de que pronto tuvo el proyecto un enfoque m\u00e1s ambicioso, los numerosos problemas t\u00e9cnicos y administrativos hicieron que las obras no avanzasen al ritmo deseado -al parecer durante el reinado de Felipe II no se ejecut\u00f3 realmente ning\u00fan tramo-, de manera que las primeras nivelaciones no comenzaron hasta la llegada al trono de Felipe IV.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos2.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>Ya con Carlos II se dan las disposiciones para continuar los trabajos y as\u00ed, en escritura otorgada en Madrid el 28 de junio de 1679, se constata que los vecinos de Ciempozuelos deb\u00edan pagar trece reales y medio por cada fanega de tierra que pudiera ser regada por la acequia. Al a\u00f1o siguiente el rey manda nivelar de nuevo todo el cauce ya ejecutado y, bajo la direcci\u00f3n del maestro mayor de obras D. Francisco Mu\u00f1oz, se excava la caja del canal -con tepes de tierra sobre suelo natural- hasta la Vereda de Matalobos; en este enclave un gran sumidero detuvo las obras, pero, con grandes esfuerzos, se logr\u00f3 hacer pasar el agua y en 1699 ya pod\u00edan regarse en la jurisdicci\u00f3n de Ciempozuelos unas 185 ha. Para ello, la villa, en documento fechado el 2 de abril del mismo a\u00f1o, se compromet\u00eda a abonar al monarca y a los fondos del caz la misma cuota que antes hab\u00eda pagado la localidad toledana de A\u00f1over, pero s\u00f3lo durante dos a\u00f1os que se contabilizar\u00edan a partir del mes de septiembre, de manera que por cada una de las 412 fanegas regadas se pagar\u00edan cinco reales.<\/p>\n<p>Tras sucesivas interrupciones e intentos de abrir un cauce nuevo, Felipe V dicta el 31 de mayo de 1738 una Instrucci\u00f3n y Reglamento para continuar los trabajos y, por orden de 26 agosto, se solicitan informes relativos al estado de la acequia; en \u00e9stos se notifica que se hab\u00edan ejecutado 11.800 varas (9.864,8 m.) correspondientes al tramo inicial desde la presa hasta el arroyo de Matalobos, y se hab\u00edan excavado otras 6.200 varas (5.183,9 m.) a lo largo del t\u00e9rmino de Ciempozuelos. Para rehabilitar el canal es nombrado director de las obras el ingeniero Sebasti\u00e1n Fering\u00e1n Cort\u00e9s, que elabora un proyecto similar en su trazado al existente, estableciendo un sistema complementario de acequias que desaguaban unas en otras y aprovechaban mejor el agua sobrante, permitiendo as\u00ed una mayor extensi\u00f3n regada. En 1740 se dictan un nuevo reglamento y ordenanzas, nombrando nuevo personal -esta vez independiente del que trabajaba en el Alc\u00e1zar de Madrid- a la vez que se definen los l\u00edmites con el Real Sitio de Aranjuez.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"8a43debbedd118dc3\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-3\" data-target=\"#8a43debbedd118dc3\" href=\"#8a43debbedd118dc3\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XVI, XVII y XVIII - II<\/span><\/a><\/h4><\/div><div id=\"8a43debbedd118dc3\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos3.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>El canal vuelve a entrar en servicio en diciembre de 1741, pero de nuevo aparecieron numerosos sumideros -sobre todo entre San Mart\u00edn de la Vega y Ciempozuelos- que lo inutilizaron (al parecer Fering\u00e1n gast\u00f3 en su reparaci\u00f3n 800.000 reales, aproximadamente un 10% del coste de la obra previamente ejecutada por \u00e9l mismo). A pesar de ello, en 1749, bajo el reinado de Fernando VI, retoma el proyecto el ingeniero Carlos de Witte, que, entre otras obras, abre dos cauces alternativos para evitar los sumideros: las acequias de Serrano y de la Media Luna. La primera nace del desaguador de Matalobos y finaliza a la altura de la Vereda de las C\u00e1rceles, la segunda tiene su inicio entre los Km. 19 y 20, y con algo m\u00e1s de 13 Km. de longitud discurre entre el canal y el r\u00edo Jarama. De esta forma se permiti\u00f3 el funcionamiento completo de la acequia durante algo m\u00e1s de un a\u00f1o, puesto que, pasado dicho tiempo, volvieron a formarse nuevos sumideros en Ciempozuelos y Sese\u00f1a; en este \u00faltimo t\u00e9rmino, por falta de recursos econ\u00f3micos, no fueron reparados. Como consecuencia de ello se determin\u00f3 conservar \u00fanicamente el riego hasta la vega de Ciempozuelos, al tiempo que la acequia de la Media Luna llevaba las aguas hasta tierra de Sese\u00f1a; el resto, a partir de la Vereda de las C\u00e1rceles, qued\u00f3 fuera de servicio, pese a que reinando ya Carlos IV se sustituy\u00f3 la tierra de los sumideros por otra de mejor calidad compactada con pisones.<\/p>\n<p>Desde el punto de vista administrativo Ciempozuelos segu\u00eda formando parte del condado de Chinch\u00f3n, hecho que no fue obst\u00e1culo para que, durante todo el siglo XVI, se reprodujeran los antiguos conflictos jurisdiccionales con Valdemoro; as\u00ed, se nombraron de com\u00fan acuerdo \u00e1rbitros que dictaron una primera sentencia -firmada por ambas partes el 18 de diciembre de 1508 en la desaparecida ermita de Santiago, lim\u00edtrofe entre las dos villas aunque perteneciente a Valdemoro-, que no dej\u00f3 satisfechas a ninguna de las localidades. Por ello iniciaron un nuevo pleito en 1550, zanjado temporalmente en 1569 tras varias sentencias y apelaciones ante la Real Chanciller\u00eda de Valladolid, hasta que esta misma instituci\u00f3n fall\u00f3 en 1588 a favor del conde de Chich\u00f3n. Como consecuencia de ello, el marqu\u00e9s de Mu\u00f1\u00f3n, se\u00f1or de Valdemoro, volvi\u00f3 a apelar ante la Chanciller\u00eda, finalizando esta larga sucesi\u00f3n de pleitos con la sentencia, favorable al duque de Lerma para Valdemoro, dictada el 15 de julio de 1603. De esta manera quedaron se\u00f1alados definitivamente los linderos entre los dos municipios.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos4.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>En cuanto a la demograf\u00eda, los primeros datos que tenemos nos los proporcionan los censos de 1530 y 1591, que arrojan cifras muy dispares: 484 y 873 vecinos respectivamente. El Catastro del marqu\u00e9s de la Ensenada, fechado en 1752, da una poblaci\u00f3n -en la que incluye 76 viudas y solteras- de 428 vecinos y especifica que s\u00f3lo uno de ellos vive en el Soto Guti\u00e9rrez, mientras que el Censo del conde de Aranda, realizado entre 1768-69, contabiliza ya 1949 habitantes. Aunque al analizar estos datos deduzcamos que las malas condiciones higi\u00e9nico-sanitarias y las epidemias eran, en buena parte, responsables del estancamiento demogr\u00e1fico de Ciempozuelos, la Descripci\u00f3n Lorenzana, unos a\u00f1os posterior al Catastro, desmiente dicha hip\u00f3tesis e indica textualmente: \u201cla situaci\u00f3n de esta villa es bastante saludable, sin experimentarse en ella contagio particular m\u00e1s que algunas tercianas\u201d, habiendo aumentado por ello la poblaci\u00f3n hasta los 500 vecinos.<\/p>\n<p>Los datos referentes a actividades econ\u00f3micas nos revelan que agricultura y ganader\u00eda eran las ocupaciones fundamentales entre los habitantes de Ciempozuelos. Por el mismo Catastro sabemos que en el secano se cultivaban cereales (trigo, cebada, centeno y avena), vi\u00f1as y olivos, mientras que en la vega, cuyas tierras \u201cse regar\u00e1n concluida la obra de la Real Acequia\u201d, la producci\u00f3n consist\u00eda en hortalizas, melones, frutales -sobre todo granadas e higueras (las brevas negras, de excelente calidad, se vend\u00edan en la Corte seg\u00fan consta en la Descripci\u00f3n Lorenzana)- y, de nuevo, olivos. La ganader\u00eda, no tan importante, contaba con caba\u00f1as de lanar, caballar, boyal y de cerda, existiendo zonas de pastos y tres sotos -de la Pe\u00f1a de San Juan, del Parral y Guti\u00e9rrez- con abundantes \u00e1lamos y chopos.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos5.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>En cuanto a la industria, el Catastro registra en Ciempozuelos cinco molinos aceiteros (tres de ellos pertenecientes a presb\u00edteros que obten\u00edan algunos beneficios con su explotaci\u00f3n), dos tener\u00edas donde se curt\u00edan pieles, un pozo de nieve propiedad del marqu\u00e9s de Arcia, una jaboner\u00eda sin uso y las conocidas Salinas de Espartinas, propiedad real que se ced\u00eda en arrendamiento a particulares y suministraba sal a la provincias del Reino de Toledo. El caser\u00edo lo formaban, de acuerdo con los datos del Catastro de Ensenada, 484 casas -todas habitables y 75 de ellas altas-, cuyos propietarios no pagaban tributo alguno por el asentamiento en el terreno. Labradores y jornaleros formaban el grueso de la poblaci\u00f3n activa, pero exist\u00edan muchas otras profesiones: en el pueblo prestaban sus servicios un m\u00e9dico, un cirujano y dos barberos sangradores, otros dos boticarios, un maestro y un preceptor de gram\u00e1tica, un buen n\u00famero de arrieros, siete pastores, un agrimensor, un tabernero y cuatro mesoneros, un tablajero (carnicero) y un obligado de carnes (encargado de su abastecimiento), un abacero (vendedor de aceite, vinagre y legumbres), cinco tenderos, once panaderos -como dato curioso merece la pena rese\u00f1ar que desde 1606 hasta 1739 Ciempozuelos estuvo obligado a contribuir al abastecimiento de la Corte con cien fanegas de pan cocido-, un chocolatero y un confitero, dos yeseros, cuatro alba\u00f1iles, dos ministros de vara que impart\u00edan justicia, un barquero en el r\u00edo Jarama a la altura de Bayona (Titulcia) y un administrador del tabaco.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"0367cb1c344b00191\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-3\" data-target=\"#0367cb1c344b00191\" href=\"#0367cb1c344b00191\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XVI, XVII y XVIII - III<\/span><\/a><\/h4><\/div><div id=\"0367cb1c344b00191\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos7.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>Adem\u00e1s, en la Real Acequia del Jarama trabajaban un guarda y un pe\u00f3n encargado de su mantenimiento, mientras que la lista de artesanos era exhaustiva: tres tejedores de lienzos, un sastre, un campanero, un tallista, un maestro zapatero, un herrador, dos curtidores, un carpintero, dos carreteros, un estambrero que trabaja la lana, un maestro botero, un guarnicionero, un herrero, y numerosos oficiales o aprendices de estos menesteres. Para finalizar, el Catastro especifica que, entre la poblaci\u00f3n, hay 25 personas calificadas como \u201cpobres mendigos\u201d.<\/p>\n<p>Si comparamos estos datos con los suministrados por el Censo de Floridablanca de 1787, observaremos algunas diferencias: ha aumentado de forma importante el n\u00famero de jornaleros y criados a costa del de labradores -s\u00f3lo 56-, y aparecen nuevas profesiones: cuatro abogados, un dependiente de la Inquisici\u00f3n, un s\u00edndico de \u00f3rdenes religiosas y 22 empleados con sueldo del Rey dedicados a oficios variados (el Censo de Aranda de 1768-69 recoge 17, de los cuales 9 -guardas, maestros y un fiel de la Real Hacienda- constitu\u00edan el vecindario de las Salinas de Espartinas), para una poblaci\u00f3n total de 1.824 habitantes.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos8.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>En lo relativo a la organizaci\u00f3n administrativa, el t\u00edtulo de conde de Chinch\u00f3n permaneci\u00f3 en el linaje original hasta que en 1683 pas\u00f3 a D. Julio Savelli Fern\u00e1ndez-Cabrera, pr\u00edncipe de Albano y fallecido sin sucesi\u00f3n. Tras un largo pleito lo obtiene el pretendiente italiano duque de Sforza, qui\u00e9n lo vende en 1738 al infante D. Felipe de Borb\u00f3n y Farnesio, hijo de Felipe V; \u00e9ste, a\u00f1os m\u00e1s tarde, en 1761, lo cede a su hermano menor, D Luis Antonio Jaime de Borb\u00f3n. Por tanto, Ciempozuelos contin\u00faa siendo una villa de se\u00f1or\u00edo, que, aunque territorialmente estaba incluida en la provincia o intendencia de Segovia, en lo religioso depend\u00eda del Arzobispado de Toledo, perteneciendo a la Vicar\u00eda General de la misma ciudad y al Arciprestazgo de Madrid. Dos de las instituciones m\u00e1s relevantes del pueblo eran el convento de religiosos de San Francisco, en la Avenida de la V. M. Antonia Mar\u00eda de la Misericordia n\u00ba 20 -actual sede de la Hermanas Oblatas-, ocupado, seg\u00fan el Censo de Floridablanca, por trece profesores, tres legos y un donado, y el convento de monjas de Santa Clara, en la Calle de Jer\u00f3nimo del Moral n\u00ba 21, que acog\u00eda a diecinueve religiosas y, como dato anecd\u00f3tico, pose\u00eda uno de los cuatro mesones de Ciempozuelos. Adem\u00e1s, la parroquia de Santa Mar\u00eda Magdalena ten\u00eda como anejo la iglesia de San Juan Bautista en las Salinas de Espartinas, existiendo otra ermita en las afueras de la villa -hoy ya integrada en el casco urbano- consagrada a Nuestra Se\u00f1ora del Consuelo.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos9.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>A pesar de permanecer bajo la jurisdicci\u00f3n del Estado de Chich\u00f3n, la localidad tuvo desde el pasado corregidor propio y el gobierno municipal, formado por alcalde, regidores, escribano, etc., era nombrado por el se\u00f1or entre las propuestas que le hac\u00eda previamente el vecindario. Entre los bienes que pertenec\u00edan al Concejo podemos citar tierras de cultivo, superficies de los sotos del Parral, de la Pe\u00f1a de San Juan y alrededores (la corta de le\u00f1a, la caza y el arrendamiento para la pesca de determinados enclaves del r\u00edo Jarama proporcionaban importantes beneficios a las arcas municipales), la Casa del Ayuntamiento, la carnicer\u00eda d\u00f3nde se ubicaba tambi\u00e9n el p\u00f3sito, la abacer\u00eda, la taberna y la pasteler\u00eda. Otro edificio significativo de Ciempozuelos era el Hospital de Nuestra Se\u00f1ora de la Concepci\u00f3n, llamado popularmente \u201cel Hospitalillo\u201d, situado en el solar actualmente ocupado por el Centro C\u00edvico-Cultural, en la calle de la Virgen 9 c\/v calle Pe\u00f1uelas, y que, adem\u00e1s de prestar una m\u00ednima asistencia sanitaria (estaba al cuidado de un presb\u00edtero y un sirviente, pero s\u00f3lo hab\u00eda cuatro enfermos internados en \u00e9l seg\u00fan datos del Censo de Floridablanca), ten\u00eda una C\u00e1tedra de Gram\u00e1tica Aneja.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos10.png\" width=\"250\" border=\"0\" data-darkreader-inline-border-top=\"\" data-darkreader-inline-border-right=\"\" data-darkreader-inline-border-bottom=\"\" data-darkreader-inline-border-left=\"\" \/>Entre los acontecimientos m\u00e1s rese\u00f1ables en este siglo XVIII podemos destacar la Guerra de Sucesi\u00f3n, en cuyo transcurso Ciempozuelos, como otras localidades, sufri\u00f3 los desmanes de las tropas del archiduque Carlos de Austria, que profanaron la ermita de San Juan Bautista en Espartinas. El propio Felipe V se hosped\u00f3 en 1706, durante el conflicto, en la llamada Casa de la Cadena, situada en la calle de los Frailes (donde, por otra parte, existieron construcciones importantes como las casas de la Indiana o la del Pr\u00edncipe P\u00edo); el edificio, ya desaparecido, ten\u00eda en su fachada principal el escudo real, tallado en granito, con las armas nacionales y la flor de lis, as\u00ed como dos gruesos pilares de piedra a ambos lados de la puerta. A\u00f1os m\u00e1s tarde, en 1710, ser\u00e1 el archiduque de Austria -futuro rey Carlos III- qui\u00e9n establezca su campamento en Ciempozuelos, donde dicta un decreto con fecha 11 de noviembre. Por \u00faltimo, el 14 de julio de 1717, festividad de San Buenaventura, nace en nuestra localidad y es bautizado en la iglesia parroquial el c\u00e9lebre arquitecto Ventura Rodr\u00edguez, que con el paso del tiempo llegar\u00eda a ser director de la Real Academia de Bellas Artes de San Fernando.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"margin-top:0px;margin-bottom:40px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:rgba(6,6,45,0);border-width: 0 0 4px 0;border-color:rgba(255,229,191,0);border-style:solid;box-shadow:0px 20px 21px -13px #000000;;padding: 60px 20px 0px 20px;\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-text fusion-text-6\" style=\"text-align:center;\"><h3><strong>SIGLOS XIX y XX<\/strong><\/h3>\n<\/div><style type=\"text\/css\">#accordion-2431-4 .fusion-panel:hover, #accordion-2431-4 .fusion-panel.hover{ background-color: rgba(249,249,249,0.9) } #accordion-2431-4 .fusion-panel { border-color:#000005; border-width:1px; background-color:rgba(249,249,249,0.9); }.fusion-accordian  #accordion-2431-4 .panel-title a .fa-fusion-box{ color: #eaeaea;}.fusion-accordian  #accordion-2431-4 .panel-title a .fa-fusion-box:before{ font-size: 27px; width: 27px;}.fusion-accordian  #accordion-2431-4 .panel-title a{font-size:15px;}.fusion-accordian  #accordion-2431-4 .fa-fusion-box { background-color: #aa7803;border-color: #aa7803;}.fusion-accordian  #accordion-2431-4 .panel-title a:hover, #accordion-2431-4 .fusion-toggle-boxed-mode:hover .panel-title a { color: #0a0a0f;}.fusion-accordian  #accordion-2431-4 .panel-title .active .fa-fusion-box,.fusion-accordian  #accordion-2431-4 .panel-title a:hover .fa-fusion-box { background-color: #0a0a0f!important;border-color: #0a0a0f!important;}<\/style><div class=\"accordian fusion-accordian\"><div class=\"panel-group\" id=\"accordion-2431-4\" role=\"tablist\"><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"01991b487ffccff5f\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-4\" data-target=\"#01991b487ffccff5f\" href=\"#01991b487ffccff5f\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XIX y XX - I<\/span><\/a><\/h4><\/div><div id=\"01991b487ffccff5f\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p style=\"font-weight: 400;\">El siglo XIX comienza con la invasi\u00f3n napole\u00f3nica y la posterior Guerra de la Independencia, durante la cual Ciempozuelos sufre importantes da\u00f1os. A\u00f1os despu\u00e9s, en 1811, las Cortes de C\u00e1diz decretan la abolici\u00f3n de los se\u00f1or\u00edos, poniendo fin de esta forma al dominio que los condes de Chinch\u00f3n hab\u00edan ejercido sobre la villa durante m\u00e1s de tres siglos, mientras que ya en 1833, la nueva divisi\u00f3n territorial del pa\u00eds supone la integraci\u00f3n de la localidad en la provincia de Madrid, dentro del partido judicial de Getafe.<\/p>\n<p style=\"font-weight: 400;\">Otros sucesos destacables en esta \u00e9poca fueron las desamortizaciones eclesi\u00e1stica y civil. La primera, decretada en 1836, no afect\u00f3 en demas\u00eda al municipio: se vendieron 16 fincas -8 del clero regular y 8 del secular- y 4 casas, pero, mientras el convento de monjas de Santa Clara continu\u00f3 ocupado por sus moradoras, el de religiosos de San Francisco fue vendido a particulares. La desamortizaci\u00f3n civil o de propios provoc\u00f3, por su parte, que un reducido n\u00famero de compradores acaparase la mayor\u00eda de los lotes subastados; entre ellos destacaban dos sotos de 53 y 75 ha. situados en El Parral, con abundante arbolado, pasto y caza.<\/p>\n<p style=\"font-weight: 400;\">El nuevo siglo trae consigo la publicaci\u00f3n de numerosos diccionarios geogr\u00e1ficos que van a ser una valiosa fuente de informaci\u00f3n sobre demograf\u00eda y aspectos socio-econ\u00f3micos de los pueblos de nuestra Comunidad. El de Sebasti\u00e1n de Mi\u00f1ano de 1826 nos da una poblaci\u00f3n para Ciempozuelos de 2.094 habitantes, que en 1848 hab\u00edan descendido a 2.060 (datos de Madoz), alcanz\u00e1ndose los 2.483 en 1889 (Mar\u00edn P\u00e9rez). Las actividades econ\u00f3micas eran pr\u00e1cticamente las mismas que en el siglo pasado: se cultivaban cereales -sobre todo cebada-, vi\u00f1as, olivos, jud\u00edas, patatas -de las que se obten\u00edan buenas cosechas-, cebollas, pimientos encarnados, alcachofas, pepinos, melones -vendidos en el mercado de Las Vistillas de Madrid-, sand\u00edas, higos, etc&#8230;, y la ganader\u00eda contaba b\u00e1sicamente con caba\u00f1as de lanar, vacuno y equino.<\/p>\n<p style=\"font-weight: 400;\">En cuanto a la industria, exist\u00edan f\u00e1bricas de salitre (una de ellas, abandonada ya a principios de siglo, pertenec\u00eda a la Real Hacienda), y segu\u00edan explot\u00e1ndose las famosas Salinas de Espartinas que surt\u00edan a los dep\u00f3sitos de Aranjuez, Toledo, San Mart\u00edn de Valdeiglesias y Madrid. La relaci\u00f3n de fincas r\u00fasticas desamortizadas en el t\u00e9rmino municipal -las Salinas hab\u00edan sido adjudicadas a un particular en 1871 por 141.000 pesetas- nos van a proporcionar informaci\u00f3n detallada de sus instalaciones: el agua mineral se obten\u00eda de un manantial que nac\u00eda al pie de las colinas y era conducida por un canal de madera que discurr\u00eda a trav\u00e9s de una galer\u00eda construida a base de mamposter\u00eda y f\u00e1brica de ladrillo. Se vert\u00eda a continuaci\u00f3n en un enorme dep\u00f3sito o recocedero de 819 m3 de capacidad, llamado de San Miguel, con fondo de greda y paredes de este mismo material y entramado de madres, y desde aqu\u00ed era distribuida a 18 albercas o vasos de cristalizaci\u00f3n -tambi\u00e9n de greda y esteras-, para desaguar finalmente, por medio de compuertas, en acequias de limpieza que vert\u00edan en un arroyo. En las m\u00e1s de 17 ha. que ocupaban las Salinas se levantaban edificios como la f\u00e1brica, con un patio central de 2.500 m2 alrededor del cual se dispon\u00edan las dependencias; la ya mencionada ermita, cuyos muros de mamposter\u00eda sustentaban una armadura de par e hilera; las casas del comandante, administrador, pesador y cabo, con patio-corral, cuadras, pajar, cueva, gallineros, c\u00e1mara y habitaciones; los dos almacenes, que pod\u00edan contener m\u00e1s de 60.000 quintales de sal y se construyeron con mamposter\u00eda reforzada por machones en talud (el mayor estaba equipado con un and\u00e9n de carga-descarga y pose\u00eda una buena armadura sostenida por nueve pies derechos); am\u00e9n de las consabidas habitaciones de los dependientes, establos, almacenes de herramientas, etc&#8230;<\/p>\n<p style=\"font-weight: 400;\">Tambi\u00e9n Emilio Mu\u00f1oz en su obra \u201cCiempozuelos\u201d, publicada en 1891, se va a hacer eco de la explotaci\u00f3n de las Salinas y se\u00f1ala al respecto que se recog\u00edan 12.000 quintales de sal en los m\u00e1s de 20 vasos que estaban en funcionamiento, siendo tambi\u00e9n abundante la thenardita (SO4 Na2), nuevo mineral descubierto a principios de siglo en el lugar; adem\u00e1s, los dos caser\u00edos inmediatos, con sus correspondientes viviendas y dependencias auxiliares, constitu\u00edan ya una importante colonia agr\u00edcola. Madoz, por su parte, rese\u00f1a un molino harinero, llamado anta\u00f1o de Matalobos y ahora del Rey, situado en el l\u00edmite de la jurisdicci\u00f3n con San Mart\u00edn de la Vega, mientras que, al finalizar el siglo, Mar\u00edn P\u00e9rez nos habla de la elaboraci\u00f3n de sosa y de la explotaci\u00f3n de las minas de sal de Glauber, por las que la localidad era conocida. Mu\u00f1oz, dos a\u00f1os despu\u00e9s que Mar\u00edn P\u00e9rez, aclara al respecto que se hab\u00edan abandonado las minas denominadas Consuelo, Amparo y Protectora, situadas en la margen izquierda del Jarama -exist\u00eda otro yacimiento en las Salinas de Espartinas-, desapareciendo tambi\u00e9n la f\u00e1brica de sales de sosa La Alcalina, de la cual quedaban las ruinas al pie del manicomio masculino, y una f\u00e1brica de jabones; pero, como contrapartida, menciona cuatro hornos de yeso, seis tahonas y una confiter\u00eda con f\u00e1brica de gaseosas y cerrer\u00eda.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"dfbda41ec766892fa\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-4\" data-target=\"#dfbda41ec766892fa\" href=\"#dfbda41ec766892fa\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XIX y XX - II<\/span><\/a><\/h4><\/div><div id=\"dfbda41ec766892fa\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos15.png\" width=\"250\" border=\"0\" \/>Todos los cronistas de la \u00e9poca coinciden en la descripci\u00f3n que hacen de Ciempozuelos, por lo que deducimos que, hasta la fundaci\u00f3n de los hospitales psiqui\u00e1tricos, las variaciones en la morfolog\u00eda urbana debieron de ser m\u00ednimas. Mi\u00f1ano destaca como construcciones m\u00e1s significativas la parroquia, los conventos, el hospital, el p\u00f3sito, un establecimiento del Real Patrimonio vinculado a la acequia del Jarama -en 1795 se unific\u00f3 su gobierno con el del Real Sitio de Aranjuez, aunque la contadur\u00eda y tesorer\u00eda, separadas, se encontraban en Ciempozuelos-, la fuente para el ganado y tres ermitas: adem\u00e1s de las ya conocidas y consagradas a San Juan Bautista y a Nuestra Se\u00f1ora del Consuelo, en el inicio del camino de Valdemoro -actual calle Jer\u00f3nimo del Moral- se levantaba la ermita de la Soledad. Cuyas im\u00e1genes formaban parte de la vistosa procesi\u00f3n del Viernes Santo, y de la que Madoz dice que \u201cnada ofrece de particular\u201d; quiz\u00e1s por esta raz\u00f3n fue sustituida desgraciadamente hace unos a\u00f1os por una moderna edificaci\u00f3n.<\/p>\n<p>El mismo cronista a\u00f1ade a la lista de Mi\u00f1ano el ayuntamiento, dos escuelas y la plaza Mayor, contabilizando un total de 300 casas, mientras que Mar\u00edn P\u00e9rez aumenta el caser\u00edo hasta 480 edificios y nos habla ya del asilo de Nuestra Se\u00f1ora del Consuelo, fundado en 1864 con el objeto de \u201crecibir a todas las pecadoras arrepentidas, cualquiera que sea su pa\u00eds, edad y condici\u00f3n que, por sus circunstancias excepcionales, no pudieran ser admitidas en otros establecimientos\u201d; la instituci\u00f3n estaba a cargo de la conocida comunidad de Oblatas del Sant\u00edsimo Redentor, que, como sabemos, hab\u00eda ocupado el edificio del antiguo convento de Franciscanos. Tambi\u00e9n menciona Mar\u00edn P\u00e9rez dos posadas, cinco escuelas (dos de ni\u00f1os, dos de ni\u00f1as y una de adultos), y por supuesto, los dos manicomios, uno para cada sexo, fundados por el recientemente canonizado San Benito Menni, hermano hospitalario de la Orden de San Juan de Dios.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos16.png\" width=\"250\" border=\"0\" \/>El manicomio masculino abr\u00eda sus puertas en 1877, ubic\u00e1ndose inicialmente en una finca situada en el extremo oriental del pueblo, pr\u00f3xima a la estaci\u00f3n de ferrocarril y colindante por el norte con la carretera de Chich\u00f3n, y sus edificaciones, en forma de T, se dispon\u00edan en continuidad formando un conjunto de patios regulares ajardinados. M\u00e1s tarde, a medida que aumentan las necesidades, el hospital adquiere nuevos terrenos (fundamentalmente el norte de los primitivos, separados de \u00e9stos por la carretera), dando lugar a un enorme recinto, cercado por tapias, en el que se sustituyen las antiguas construcciones por pabellones aislados y se levanta un gran n\u00famero de dependencias auxiliares -molinos, lagar, graneros, vaquer\u00eda, talleres, huerta, etc&#8230;- que posibilitan su funcionamiento como entidad aut\u00f3noma, a modo de peque\u00f1a ciudad dentro del casco de Ciempozuelos.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos17.png\" width=\"250\" border=\"0\" \/>En cuanto al manicomio femenino, su fundaci\u00f3n m\u00e1s tard\u00eda -1881- y el hecho de que no estuviesen sus dependencias explican que tanto Mar\u00edn P\u00e9rez como Mu\u00f1oz sean mucho m\u00e1s escuetos en sus descripciones. Se situ\u00f3 en el borde sureste del n\u00facleo de poblaci\u00f3n, ocupando una superficie menor que la del hospital masculino, y limitaba al norte con la calle de la Virgen y al sur con el barrio de cuevas del Prado. La organizaci\u00f3n constructiva era la ya conocida a base de pabellones yuxtapuestos configurando patios m\u00e1s peque\u00f1os que los del manicomio de hombres y, aunque Mar\u00edn P\u00e9rez relata que exist\u00edan dependencias generales y una huerta, Mu\u00f1oz, en 1891, nos aclara que no hab\u00eda ninguna de estas instalaciones. Tanto la administraci\u00f3n como la asistencia personal a las enfermas y la limpieza de los edificios estaba encomendada a las Hermanas Hospitalarias del Sagrado Coraz\u00f3n de Jes\u00fas, mientras que de la farmacia se encargaban los funcionarios del hospital masculino; adem\u00e1s, tal y como suced\u00eda en \u00e9ste, buena parte de los pacientes estaban pensionados por la Diputaci\u00f3n Provincial.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"cabdb68bb2b165333\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-4\" data-target=\"#cabdb68bb2b165333\" href=\"#cabdb68bb2b165333\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XIX y XX - III<\/span><\/a><\/h4><\/div><div id=\"cabdb68bb2b165333\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos18.png\" width=\"250\" border=\"0\" \/>Respecto al cap\u00edtulo de infraestructuras, Ciempozuelos, a pesar del origen de su nombre, hab\u00eda tenido siempre dificultades para abastecerse de agua potable y, seg\u00fan relata Mi\u00f1ano a principios de siglo, s\u00f3lo dispon\u00eda de la que le proporcionaba el r\u00edo Jarama. Posteriormente se surti\u00f3 mediante cubas transportadas desde el vecino t\u00e9rmino de Valdemoro y, por los datos proporcionados por Mu\u00f1oz, sabemos que el agua no lleg\u00f3 definitivamente al pueblo -procedente esta vez del paraje llamado La Ontanilla, en Torrej\u00f3n de Velasco- hasta el 13 de marzo de 1890. Como consecuencia de ello, el lavadero p\u00fablico y el abrevadero de ganado, situados a espaldas de la manzana sur de la plaza Mayor y cuyas condiciones higi\u00e9nicas -en parte por la proximidad del antiguo matadero instalado en el p\u00f3sito- dejaban mucho que desear, fueron trasladados el mismo a\u00f1o 1890 al este de la iglesia, donde se construy\u00f3 un tercer pil\u00f3n para el lavado de la ropa con jab\u00f3n. M\u00e1s tarde se proceder\u00e1 a la remodelaci\u00f3n de la antigua plaza de la Iglesia, para lo cual se derriban la vivienda y los corrales situados en su frente oriental, de manera que el nuevo recinto, rebautizado como plaza de Ventura Rodr\u00edguez, pueda acoger la fuente de aguas potables que, coronada por la estatua del arquitecto y fechada en 1898, existe actualmente. El monumento, cuyo autor fue J. Lluch, lleva en su pedestal cuatro l\u00e1pidas que rememoran algunas de las obras proyectadas por el arquitecto en la capital: las fuentes de Cibeles, Neptuno y las Cuatro Estaciones, y la iglesia de San Marcos.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos19.png\" width=\"250\" border=\"0\" \/>El alumbrado, por su parte, lleg\u00f3 a Ciempozuelos en septiembre de 1889, mientras que, en lo relativo a comunicaciones, el panorama descrito por Madoz a mediados de siglo no es demasiado halag\u00fce\u00f1o: nos indica que los caminos que se dirigen a las localidades lim\u00edtrofes est\u00e1n en mal estado de conservaci\u00f3n, rese\u00f1ando como v\u00eda m\u00e1s importante la carretera general de Madrid a Andaluc\u00eda, que pasa a \u00bc de legua del pueblo. En ella exist\u00edan un ventorrillo con una peque\u00f1a habitaci\u00f3n, y la casa de postas, constituida en su mayor parte por cuadras para los tiros de diligencias. Mu\u00f1oz, a\u00f1os despu\u00e9s es m\u00e1s expl\u00edcito en su cr\u00f3nica y de ella deducimos que se han producido algunas mejoras: en 1881 se efectu\u00f3 la recepci\u00f3n oficial de la carretera de tercer orden, estatal, que comunicaba Ciempozuelos con Titulcia y Chinch\u00f3n; adem\u00e1s, la provincial n\u00ba 7, tambi\u00e9n de tercer orden, enlazaba con la general de Andaluc\u00eda, figurando as\u00ed mismo en el plan de carreteras la n\u00ba 36 que, desde la Cuesta de la Reina y en direcci\u00f3n sur-norte, deb\u00eda llegar a San Mart\u00edn de la Vega.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos20.png\" width=\"250\" border=\"0\" \/>A pesar de ello, el acontecimiento m\u00e1s relevante del siglo en materia de comunicaciones fue, sin duda, la construcci\u00f3n de la v\u00eda f\u00e9rrea Madrid-Aranjuez. Los primeros pasos al respecto los hab\u00eda dado ya el marqu\u00e9s viudo de Pontejos en 1829, realiz\u00e1ndose estudios y reconocimientos del terreno que se materializaron en un proyecto de 1830, pero problemas de financiaci\u00f3n hicieron fracasar sus intentos; m\u00e1s tarde, en 1844, D. Pedro de Lara obtuvo una primera concesi\u00f3n para una l\u00ednea Madrid-Aranjuez que se pretend\u00eda prolongar hasta Alicante y caduc\u00f3 as\u00ed mismo por falta de capital para ponerla en marcha. En este momento, surge la figura del marqu\u00e9s de Salamanca, qui\u00e9n obtiene una nueva concesi\u00f3n el 6 de abril de 1845 y constituye una sociedad an\u00f3nima en la que la participaci\u00f3n extranjera es importante. Salamanca contrata al ingeniero D. Pedro Miranda, que ser\u00e1 auxiliado por los ingleses hermanos Green en el proyecto final, y el 4 de mayo de 1846 comienzan las obras. Aunque de los 25 obreros que inician la explanaci\u00f3n se pasa en poco tiempo a casi 6.000, dificultades de todo tipo hacen que los trabajos se paralicen a finales de 1847, exili\u00e1ndose el marqu\u00e9s en junio del a\u00f1o siguiente, y no ser\u00e1 hasta su regreso a Espa\u00f1a, en 1849, cuando se reanuden las obras, que cuentan ahora con un nuevo ingeniero, el franc\u00e9s Eug\u00e8ne Flachat. En 1850 se conclu\u00edan \u00e9stas, efectu\u00e1ndose un viaje de prueba, precisamente hasta Ciempozuelos, que fue todo un \u00e9xito, y el 9 de febrero de 1851 la reina Isabel II y el gobierno en pleno, presidido por Bravo Murillo, realizaron, por fin, el viaje inaugural de ida y vuelta, con lo cual se pon\u00eda en funcionamiento el que iba a ser el primer ferrocarril de nuestra provincia. Es evidente que para todas las localidades del trayecto el nuevo medio de transporte iba a suponer el comienzo de una serie de transformaciones socioecon\u00f3micas de alcance inimaginable: basta con se\u00f1alar que en el itinerario Madrid-Ciempozuelos realizado en diligencia se invert\u00edan alrededor de cinco horas de viaje, mientras que los tres trenes diarios que sal\u00edan de Atocha, con capacidad de hasta 690 personas, empleaban unos cincuenta minutos.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"67f0240fce760b156\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-4\" data-target=\"#67f0240fce760b156\" href=\"#67f0240fce760b156\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XIX y XX - IV<\/span><\/a><\/h4><\/div><div id=\"67f0240fce760b156\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos21.png\" width=\"250\" border=\"0\" \/>Todas las descripciones m\u00e1s o menos pormenorizadas de la localidad efectuadas por los cronistas del siglo XIX se corresponden con el plano realizado hacia 1860-70 por la Junta General de Estad\u00edstica con objeto de editar una Topograf\u00eda Catastral de Espa\u00f1a. En \u00e9l, se nos muestra el n\u00facleo de poblaci\u00f3n organizado en manzanas, con la parcelaci\u00f3n interior de \u00e9stas y los nombres de las calles, as\u00ed como las fincas r\u00fasticas numeradas con la indicaci\u00f3n de los distintos tipos de cultivo. Desde la estaci\u00f3n de ferrocarril, emplazada en el extremo oriental del pueblo y alejada del centro, parten dos v\u00edas m\u00e1s o menos paralelas que conducen a las plazas de Ciempozuelos: el camino Nuevo -m\u00e1s tarde carretera de Chinch\u00f3n y actualmente avenida de San Juan de Dios-, en direcci\u00f3n a la plaza Mayor, y el paseo de la Estaci\u00f3n, que, bordeado de acacias, nos llevaba a la plaza de la Iglesia o de Ventura Rodr\u00edguez. Al sur del paseo de la Estaci\u00f3n y hasta el arroyo de San Cosme se extend\u00eda una amplia superficie de terreno destinada a huertas y tierras de cultivo, y pr\u00f3ximo a ellas, junto al Cordel de las Merinas, encontramos el Cebadero, de grandes dimensiones. La plaza Mayor o de la Constituci\u00f3n era l\u00f3gicamente el nudo del que part\u00edan las v\u00edas m\u00e1s importantes, entre las que destacaba la calle Grande -hoy Jer\u00f3nimo del Moral-, aut\u00e9ntica espina dorsal del pueblo donde, adem\u00e1s de los edificios ya conocidos, se levantaban, seg\u00fan nos informa a\u00f1os despu\u00e9s Mu\u00f1oz, las escuelas de ni\u00f1os del distrito Norte (Soledad) y el matadero municipal, y cuya prolongaci\u00f3n hacia el norte era el conocido camino de Valdemoro. A la derecha de \u00e9ste y ya separado del casco urbano se localiza el min\u00fasculo barrio de las Cuevas de la Barrera, junto al que exist\u00edan unas canteras de piedra, mientras que volviendo a la plaza y en direcci\u00f3n oeste nac\u00edan la calle del Marqu\u00e9s (la duquesa viuda de Santo\u00f1a pose\u00eda all\u00ed una casa de labor con bodega, graneros, pajares y caballerizas) y la calle de la Pasteler\u00eda, en cuyo \u00faltimo tercio, de acuerdo con los datos del mismo Mu\u00f1oz, hab\u00eda una fuente de cuatro ca\u00f1os dorados. Hacia el sur y siempre desde la plaza Mayor encontramos la calle del Pr\u00edncipe, que nos conduc\u00eda al segundo barrio de viviendas con que contaba Ciempozuelos: el de las Cuevas del Prado (en 1887 el n\u00famero total de cuevas rondaba las cien).<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos22.png\" width=\"250\" border=\"0\" \/>La plaza de Ventura Rodr\u00edguez no ten\u00eda todav\u00eda el trazado actual, pero de ella part\u00eda en direcci\u00f3n poniente la calle de San Sebasti\u00e1n, en la que, seg\u00fan Mu\u00f1oz, se concentraban los mejores edificios del pueblo, \u201cde dos pisos la inmensa mayor\u00eda, en correcta alineaci\u00f3n, con variado balconaje\u201d. Entre ellos destacaban la escuela de ni\u00f1as, adquirida por el municipio en 1881, \u201ccon magn\u00edfica puerta de entrada y soberbio balc\u00f3n sobre ella\u201d, y el desaparecido Teatro Ventura Rodr\u00edguez, sede de la Sociedad Dram\u00e1tica e inaugurado el 1 de enero de 1891 con 300 localidades, \u201cbonita embocadura (&#8230;), un caprichoso y bien pintado tel\u00f3n de boca, y varias decoraciones al temple\u201d.<\/p>\n<p>Otras v\u00edas importantes que aparecen en el plano de la Junta General de Estad\u00edstica son la calle de la Virgen, paralela y en su \u00faltimo tramo, cerca ya de la ermita de Nuestra Se\u00f1ora del Consuelo, concluyente con la calle de San Sebasti\u00e1n, y la calle de las Pe\u00f1uelas, en direcci\u00f3n NO-SE desde la plaza Ventura Rodr\u00edguez, donde encontramos el ya conocido hospital de la Pur\u00edsima Concepci\u00f3n, del que Mu\u00f1oz destaca sus \u201cvarias salas para cirug\u00eda y medicina (&#8230;); abundantes y bien acondicionadas camas; m\u00e9dico, medicinas y alimentos para los pobres enfermos\u201d. Por la rese\u00f1a del cronista deducimos que su situaci\u00f3n hab\u00eda mejorado en los \u00faltimos a\u00f1os, ya que estaba subvencionado por el Ayuntamiento y el vecindario contribu\u00eda en su mantenimiento con suscripciones, rifas, donativos, etc&#8230; Cerca del hospital se hallaba la tambi\u00e9n desaparecida casa-escuela de ni\u00f1os del distrito del Sur (Consuelo), con el escudo episcopal sobre la puerta por ser un legado del obispo D. Manuel Artalejo.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos23.png\" width=\"250\" border=\"0\" \/>Esta trama urbana, jerarquizada y organizada radialmente desde las dos plazas del pueblo, se ve acompa\u00f1ada de calles secundarias y fondos de saco en los que se encuentran las entradas de cuadras, corrales y dem\u00e1s dependencias agropecuarias, imprescindibles para el desarrollo econ\u00f3mico del lugar. Adem\u00e1s, hab\u00eda bastantes huertas e higueras hacia el sur, y rodeaban el casco por esta misma orientaci\u00f3n y por el oeste numerosas eras, muy concurridas en verano por los trilladores, mientras que los caminos que part\u00edan del pueblo nos llevaban a las fincas de cultivo y uno de ellos, por poniente, hasta unas canteras cercanas. Recordemos que en el t\u00e9rmino municipal se pod\u00edan localizar importantes caser\u00edos, ya citados por Madoz: los sotos de Guti\u00e9rrez y del Parral con sus respectivas casas, donde la caza era abundante, las casas de San Ant\u00f3n o la casa del Conde, antiguo caser\u00edo de Atar\u00e9s y propiedad del conde hom\u00f3nimo.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"bb952f34dec9e2213\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-4\" data-target=\"#bb952f34dec9e2213\" href=\"#bb952f34dec9e2213\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XIX y XX - V<\/span><\/a><\/h4><\/div><div id=\"bb952f34dec9e2213\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos24.png\" width=\"250\" border=\"0\" \/>Si comparamos el plano realizado por la Junta General de Estad\u00edstica con el elaborado en 1923 por el Instituto Geogr\u00e1fico observaremos importantes novedades. En primer lugar destaca la presencia en la trama de los dos hospitales psiqui\u00e1tricos establecidos en Ciempozuelos desde finales del siglo anterior: el masculino ocupa una superficie mayor que la del casco urbano y se organiza en varias manzanas; la mayor, en la que, adem\u00e1s de los pabellones, exist\u00edan huertos, jardines y vi\u00f1as, ten\u00eda un per\u00edmetro irregular, lindando sus tapias por el este con la v\u00eda f\u00e9rrea. El femenino, por su parte, ocupaba otras tres manzanas de superficie similares, perfectamente integradas en el tejido urbano y separadas entre s\u00ed por las calles Jardines y Coraz\u00f3n de Jes\u00fas, y limitaba al sur con un \u00e1rea m\u00e1s degradada. Colindante con el barrio de las Cuevas del Prado, donde abundaban los vac\u00edos urbanos y las callejuelas tortuosas.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos25.png\" width=\"250\" border=\"0\" \/>En las afueras del pueblo, junto a la ermita de Nuestra Se\u00f1ora del Consuelo, de la cual toma el nombre, encontramos un nuevo conjunto de cuevas -por tanto, con las de la Barrera, eran ya tres los asentamientos de este tipo-, mientras que al norte, una vez finalizada la calle Jer\u00f3nimo del Moral, comenzaba el paseo arbolado que nos conduc\u00eda al cementerio. El antiguo, junto a la iglesia, era de reducido tama\u00f1o y el gobernador civil de la provincia, al visitar Ciempozuelos en 1885 con motivo de la epidemia de c\u00f3lera, orden\u00f3 su inmediata clausura. En principio se encarg\u00f3 el Ayuntamiento de elaborar el proyecto y convocar la pertinente subasta, pero finalmente fue la parroquia quien llev\u00f3 a cabo su construcci\u00f3n en un enclave situado a unos 400 m. del borde urbano, inaugur\u00e1ndose en 1891. Su per\u00edmetro es irregular y adosados al muro norte encontramos un conjunto de edificaciones y \u00e1reas diferenciadas, como la capilla de las Oblatas, el pante\u00f3n de la familia Artalejo, fechado en 1893, o los recintos de enterramiento para las Hermanas Hospitalarias del Sagrado Coraz\u00f3n de Jes\u00fas y para los Hermanos de San Juan de Dios, separados por la llamada capilla de los frailes. El cementerio tiene tambi\u00e9n alg\u00fan pante\u00f3n interesante, as\u00ed como un curioso monumento a los Ca\u00eddos, de forma c\u00fabica y formado por ocho piezas de hormig\u00f3n visto separadas superficialmente por bandas de terrazo m\u00e1s oscuras. M\u00e1s tarde, adosado al norte, se construy\u00f3 un segundo camposanto, propiedad de la Orden de San Juan de Dios y reservado para los religiosos y enfermos del hospital.<\/p>\n<p>Los datos de poblaci\u00f3n que nos proporciona Ortega Rubio correspondientes al censo de 1910 dan una idea de la relevancia que ten\u00edan ya los dos hospitales psiqui\u00e1tricos y el asilo en el municipio: de los 5.271 habitantes registrados, s\u00f3lo 3.631 lo eran de derecho, A pesar de ello, el incremento demogr\u00e1fico respecto a las cifras del siglo pasado hab\u00eda sido notorio, en buena parte gracias a la llegada del ferrocarril, que aument\u00f3 notablemente la riqueza del lugar (Ortega Rubio dice al respecto que era uno de los pueblos mejor administrados de la provincia, habiendo entrado \u201cen un per\u00edodo de verdadero progreso\u201d).<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"8da782fd930af5c30\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-4\" data-target=\"#8da782fd930af5c30\" href=\"#8da782fd930af5c30\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XIX y XX - VI<\/span><\/a><\/h4><\/div><div id=\"8da782fd930af5c30\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos25.png\" width=\"250\" border=\"0\" \/>La vega del Jarama proporcionaba los recursos econ\u00f3micos habituales y, pese a que las \u00faltimas d\u00e9cadas del siglo XIX son de poca actividad en las obras del canal, en 1910 se acometer\u00e1 por fin su prolongaci\u00f3n a partir del entronque con la acequia de la Media Luna y siguiendo el trazado original que se hab\u00eda abandonado en el pasado. En a\u00f1os sucesivos se van completando distintos tramos, a la vez que se procede a la reparaci\u00f3n y revestimiento de los ya existentes -para salvar el paso en la zona de sumideros hubo que construir finalmente un acueducto formado por secciones de hormig\u00f3n en U-, con objeto de llevar el riego hasta tierras toledanas, tal y como preve\u00eda el proyecto primitivo. De las edificaciones antiguas todav\u00eda se conservan en el t\u00e9rmino de Ciempozuelos algunas casas de guardas -con sus muros encalados y refuerzos de ladrillo en esquinas y huecos-, as\u00ed como tramos de la propia acequia donde la f\u00e1brica de ladrillo vista se ve interrumpida, aproximadamente cada 20 metros, por cadenas de mamposter\u00eda.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos27.png\" width=\"250\" border=\"0\" \/>Durante la Guerra Civil Ciempozuelos permanece bajo dominio republicano hasta que el 6 de febrero de 1937, en plena batalla del Jarama, cae en manos del ej\u00e9rcito nacional. Los combates se sucedieron en la zona hasta el d\u00eda 25 -el cercano cerro del Pingarr\u00f3n, que dominaba la carretera de San Mart\u00edn de la Vega a Morata de Taju\u00f1a, fue uno de los objetivos m\u00e1s codiciados- y como al finalizar la batalla ninguno de los dos bandos hab\u00eda logrado sus objetivos, el pueblo permaneci\u00f3 pr\u00e1cticamente en l\u00ednea de fuego hasta el fin de la guerra. Adem\u00e1s de las p\u00e9rdidas humanas, las materiales tambi\u00e9n fueron cuantiosas: edificios como la iglesia parroquial o el convento de Clarisas sufrieron importantes da\u00f1os y el censo de 1940 -5.300 habitantes- refleja un ligero descenso en la poblaci\u00f3n respecto a a\u00f1os pasados. Pero esta situaci\u00f3n fue transitoria ya que las d\u00e9cadas siguientes van a suponer una \u00e9poca de importante desarrollo econ\u00f3mico y urbano, con un crecimiento generalizado hasta mediados de los a\u00f1os 60. Hacia el norte el caser\u00edo se extendi\u00f3 por ejes ya consolidados en el pasado -calles Jer\u00f3nimo del Moral y Amargura (hoy Santa Clara)- o teniendo como l\u00edmite nuevos viarios -calle Colegiata- que defin\u00edan un per\u00edmetro urbano anguloso e irregular. Por el oeste, sin embargo, encontramos algunas actuaciones planificadas en la posguerra, como el grupo de 50 viviendas unifamiliares Jos\u00e9 Antonio, que dieron lugar a un borde bien delimitado en direcci\u00f3n norte-sur: la calle de las Estrellas. Para finalizar, en el sur el crecimiento se materializ\u00f3 a espaldas de las cuevas del Prado, con manzanas muy alargadas y de poco fondo que llegan a las calles Palomero, Amapola o Margarita, a la vez que se colmataba el destartalado entramado urbano -calles del Dr. Andrajo, Pintor, San Pedro&#8230;- situado junto al hospital femenino. Este desarrollo m\u00e1s o menos anular se ve\u00eda frenado en el sector oriental por la presencia del hospital masculino, las huertas situadas al sur de \u00e9ste y, por supuesto, la v\u00eda f\u00e9rrea.<\/p>\n<p>Todo el crecimiento urbano descrito anteriormente tiene su reflejo, como es l\u00f3gico, en el censo de poblaci\u00f3n que nos proporciona el Diccionario Geogr\u00e1fico de Espa\u00f1a: 9.003 habitantes en septiembre de 1958, entre los que se incluyen nada menos que 3.713 personas recluidas en los manicomios y en el asilo de Oblatas. La misma fuente rese\u00f1a que, en compacto, hab\u00eda 651 edificios destinados a vivienda, 48 a otros usos y 313 chozos, detect\u00e1ndose importantes mejoras desde 1940: las calles estaban pavimentadas y con red de alcantarillado, hab\u00eda sido ampliado el alumbrado p\u00fablico y se hab\u00edan construido algunas viviendas protegidas as\u00ed como un grupo escolar (el existente en el Parque del Pilar, junto a la iglesia). Ace\u00f1a y Muro, autores de la \u201cGeograf\u00eda M\u00e9dica de Ciempozuelos\u201d publicada en 1953, nos proporcionan m\u00e1s datos al respecto: la citada escuela -hab\u00eda otras cinco m\u00e1s- se estaba levantando en esas fechas en el mismo lugar que antes ocuparon el lavadero y el abrevadero municipales, por lo que \u00e9ste hab\u00eda sido sustituido por uno nuevo (no as\u00ed el lavadero).<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos28.png\" width=\"250\" border=\"0\" \/>El abastecimiento de aguas se efectuaba desde Gri\u00f1\u00f3n -a partir de 1926- y Valdemoro, y en el pueblo se contabilizaban hasta cinco fuentes de las que se surt\u00edan sus habitantes, puesto que s\u00f3lo un reducido n\u00famero de casas contaba con agua corriente. Por lo general en casi todas las viviendas hab\u00eda pozos de aguas salitrosas, s\u00f3lo empleadas en los trabajos dom\u00e9sticos, y los ya conocidos manantiales de Buzanca segu\u00edan proporcionando el l\u00edquido elemento a los servicios sanitarios del manicomio masculino.<\/p>\n<p>La misma \u201cGeograf\u00eda M\u00e9dica\u201d cita como construcciones importantes, adem\u00e1s de las ya conocidas, el Ayuntamiento con su torre del reloj, dos cinemat\u00f3grafos habilitados como salas de fiestas, la Casa-Cuartel de la Guardia Civil, el edificio de Correos y Tel\u00e9grafos, y el de Tel\u00e9fonos. De la vieja cl\u00ednica-hospital de Nuestra Se\u00f1ora de la Concepci\u00f3n se nos dice que pertenec\u00eda a la Diputaci\u00f3n Provincial, resultando ya insuficiente para Ciempozuelos, que necesitaba por esas fechas un hospital m\u00e1s amplio y con servicios m\u00e1s completos.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"6a593442ab34da7c2\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-4\" data-target=\"#6a593442ab34da7c2\" href=\"#6a593442ab34da7c2\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XIX y XX - VII<\/span><\/a><\/h4><\/div><div id=\"6a593442ab34da7c2\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos29.png\" width=\"250\" border=\"0\" \/>En lo relativo a actividades econ\u00f3micas, la agricultura contin\u00faa desempe\u00f1ando un papel fundamental. La propiedad de las tierras estaba bastante repartida y en las 1.484 ha. de regad\u00edo -superficie similar a la existente a finales del siglo XIX-, aparte de los productos tradicionales, encontramos otros como el ma\u00edz, los esp\u00e1rragos o la remolacha, que se destina \u00edntegramente a la f\u00e1brica de az\u00facar de La Poveda; adem\u00e1s, a principios de los 50, se inici\u00f3 una campa\u00f1a para incrementar la producci\u00f3n de fruta. El Diccionario Geogr\u00e1fico menciona las consabidas caba\u00f1as ganaderas y cinco granjas av\u00edcolas, mientras que, en el cap\u00edtulo destinado a miner\u00eda, destacan las antiqu\u00edsimas Salinas de Espartinas: dos largas galer\u00edas, llamadas Mina Grande y Mina Chica, penetraban en la formaci\u00f3n yesosa de la monta\u00f1a y mediante toscos canales de madera, tal y como se hac\u00eda en el pasado, el agua era conducida a las doce balsas de evaporaci\u00f3n, obteni\u00e9ndose unos 30 o 40 vagones de sal com\u00fan y 15 de sulfato s\u00f3dico, datos \u00e9stos proporcionados por la \u201cGeograf\u00eda M\u00e9dica de Ciempozuelos\u201d.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos30.png\" width=\"250\" border=\"0\" \/>Tambi\u00e9n se explotaban unas canteras de arena y grava en la ribera del Jarama, junto a la carretera de Titulcia, as\u00ed como otras de yeso, a unos 800 m. al sur del pueblo, raz\u00f3n por la cual funcionaba una peque\u00f1a f\u00e1brica de este material con un horno y un molino accionados por motor el\u00e9ctrico (el Diccionario Geogr\u00e1fico, cuatro a\u00f1os despu\u00e9s, habla ya de dos f\u00e1bricas). El resto de establecimientos industriales lo formaban una tener\u00eda para el curtido de pieles, varios molinos de aceite y harina, una f\u00e1brica de hielo llamada \u201cEl Polo Norte\u201d, otras de vinos, aguardientes y alcoholes, dos de gaseosas, una de quesos -al sur del casco urbano-, una de losetas y tubos de cemento -F\u00e1brega-, otra de tejas y ladrillo, y para finalizar, las dos de mayor entidad: COCSA, que fabricaba piensos compuestos y est\u00e1 situada frente a la estaci\u00f3n ferrocarril, y la desaparecida \u201cSociedad An\u00f3nima Malter\u00eda de Nuestra Se\u00f1ora de los \u00c1ngeles\u201d, en la calle Doctor Rivas, cuya producci\u00f3n (60.000 kg. diarios de malta) se enviaba a Madrid a la f\u00e1brica de cervezas \u201cEl \u00c1guila\u201d y a la de diet\u00e9ticas infantiles \u201cMax\u201d. En ella trabajaban adem\u00e1s del equipo directivo y el personal administrativo, 45 obreros, y dispon\u00eda de talleres propios de carpinter\u00eda y mec\u00e1nica para reparar la maquinaria en uso.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos31.png\" width=\"250\" border=\"0\" \/>Este t\u00edmido proceso industrializador iniciado en Ciempozuelos en los a\u00f1os 50 va a tener continuaci\u00f3n en las d\u00e9cadas siguientes, gracias a su favorable situaci\u00f3n geogr\u00e1fica y a las buenas comunicaciones con la capital. Hasta finales de los a\u00f1os 70 surgir\u00e1n nuevos asentamientos en las proximidades del casco urbano -frente a la colonia de San Benito se instal\u00f3 la f\u00e1brica de pan Pancisa, y al NO, apoyado por la carretera M-404, encontramos el pol\u00edgono industrial \u201cLos Huertecillos\u201d, sede de la ya citada F\u00e1brega y de la granja Dos Torres, que tras ser vendida fabric\u00f3 bolsos-, mientras que junto a la carretera de Andaluc\u00eda, a lo largo de los dos kil\u00f3metros escasos que discurren por el t\u00e9rmino, se construyen una f\u00e1brica de yesos y escayolas, una granja de cerdos, almacenes de tejidos, etc&#8230;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos32.png\" width=\"250\" border=\"0\" \/>Paralelamente se produce, como es l\u00f3gico, un nuevo crecimiento del caser\u00edo, que tendr\u00e1 en el sector oeste -barrio de Bel\u00e9n- su mejor exponente, aunque tambi\u00e9n encontramos otros ejemplos al norte, como las viviendas unifamiliares del barrio de la Soledad (nueve de ellas se reservar\u00e1n para maestros) o la colonia de San Benito (para los trabajadores de F\u00e1brega). Es la \u00e9poca del suelo barato, el despegue de las viviendas en bloque y la continua aparici\u00f3n de promociones como Covalsa, Muro S.A., Burgos, Residencial Nilo, Ontasa, etc&#8230;, aunque al mismo tiempo subsisten tipolog\u00edas propias del pasado: a principios de los 80 todav\u00eda se contabilizaban m\u00e1s de 70 cuevas.<\/p>\n<p>Todo ello ha hecho de Ciempozuelos uno m\u00e1s de los municipios que componen el cintur\u00f3n industrial del sur de Madrid, a la vez que una ciudad-dormitorio que se beneficia de su cercan\u00eda a la capital y ha visto c\u00f3mo su poblaci\u00f3n segu\u00eda aumentando durante los \u00faltimos a\u00f1os.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"e23120eeb0670dfbe\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-4\" data-target=\"#e23120eeb0670dfbe\" href=\"#e23120eeb0670dfbe\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XIX y XX - VIII<\/span><\/a><\/h4><\/div><div id=\"e23120eeb0670dfbe\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p style=\"font-weight: 400;\">As\u00ed mismo, en el medio rural tambi\u00e9n han sido numerosas las transformaciones. Aunque el sector primario acusa una fuerte tendencia a la baja, todav\u00eda existen importantes instalaciones agropecuarias, fundamentalmente en las grandes fincas hist\u00f3ricas situadas en la vega del Jarama (algunas de ellas, como el Soto Guti\u00e9rrez, cr\u00edan todav\u00eda reses bravas). Yacimientos anta\u00f1o important\u00edsimos como el de Salinas de Espartinas, han sido definitivamente abandonados, desapareciendo con ellas los caser\u00edos y la antigua ermita de San Juan Bautista. Por su parte, la f\u00e1brica de az\u00facar de La Poveda se mantuvo en funcionamiento hasta la campa\u00f1a 1971-72 y al cerrar sus instalaciones, dej\u00f3 de circular el ferrocarril de v\u00eda estrecha, derrib\u00e1ndose la estaci\u00f3n a\u00f1os despu\u00e9s.<\/p>\n<p style=\"font-weight: 400;\">Respecto al sector terciario, es actualmente el mayoritario, proporcionando trabajo a un 61,7% de la poblaci\u00f3n activa, aunque, siguiendo la tendencia general, conforme aumenta el n\u00famero de establecimientos, disminuye progresivamente el de empleos. Tambi\u00e9n es significativo el campo de la construcci\u00f3n, por la alta demanda de viviendas -en un gran porcentaje unifamiliares- experimentada los \u00faltimos a\u00f1os.<\/p>\n<p style=\"font-weight: 400;\">El instrumento de planeamiento vigente en Ciempozuelos son las Normas Subsidiarias. El modelo de ordenaci\u00f3n no ha variado sustancialmente con relaci\u00f3n al dise\u00f1ado por el anterior planeamiento y as\u00ed, en lo relativo a accesibilidad, plantea descongestionar la malla viaria mediante un cintur\u00f3n de ronda que sirva de complemento a la variante de la M-404, ejecutada durante el per\u00edodo de vigencia de las \u00faltimas normas para evitar el tr\u00e1nsito de veh\u00edculos en el interior del casco. Por otra parte se pretende potenciar el uso de ferrocarril, raz\u00f3n por la cual se ha construido recientemente un nuevo aparcamiento en la estaci\u00f3n de cercan\u00edas, que ha visto c\u00f3mo aumentaba casi un 40% el n\u00famero de viajeros entre 1994 y 1998.<\/p>\n<p style=\"font-weight: 400;\">El suelo industrial se situar\u00e1 fuera del cintur\u00f3n de ronda para evitar conflictos con las \u00e1reas residenciales, apoy\u00e1ndose en la carretera M-404 y en las infraestructuras ya presentes al NO, en el actual pol\u00edgono, de forma que el suelo vacante ofertado por las Normas superar\u00e1 al ocupado por las industrias ya en funcionamiento. Adem\u00e1s, en la carretera de Andaluc\u00eda se ha reservado una superficie de otras 2.000 ha. para crear en el futuro un parque empresarial que incluir\u00e1 zonas industriales y de ocio.<\/p>\n<p style=\"font-weight: 400;\">El crecimiento del suelo residencial se planifica mayoritariamente en el interior de la ronda, en los bordes sur y oeste, buscando la deseable continuidad con la red viaria existente, a la vez que se conserva la trama del casco antiguo y se promueven algunas operaciones de reforma interior encaminadas a modificar alineaciones, permeabilizar manzanas de excesivo tama\u00f1o para obtener espacios p\u00fablicos o renovar edificaciones inadecuadas.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-toggle-no-divider fusion-toggle-boxed-mode\" role=\"tabpanel\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\"><a aria-expanded=\"false\" aria-selected=\"false\" aria-controls=\"7174a52f15305f7a5\" role=\"tab\" data-toggle=\"collapse\" data-parent=\"#accordion-2431-4\" data-target=\"#7174a52f15305f7a5\" href=\"#7174a52f15305f7a5\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">SIGLOS XIX y XX - IX<\/span><\/a><\/h4><\/div><div id=\"7174a52f15305f7a5\" class=\"panel-collapse collapse \"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div class=\"page-header\">\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos36.png\" width=\"250\" border=\"0\" \/>Tambi\u00e9n se presta especial atenci\u00f3n a las dotaciones, con propuestas ya materializadas como la Ciudad Deportiva, en el camino de la Cuesta, al sur del casco, donde se han edificado el nuevo pabell\u00f3n cubierto, pistas polideportivas, campos de f\u00fatbol y piscinas; la residencia de ancianos \u201cCasa Quinta\u201d, junto al hospital psiqui\u00e1trico, y el mencionado aparcamiento de la estaci\u00f3n de ferrocarril. Esta pol\u00edtica no es sino continuaci\u00f3n de la emprendida en d\u00e9cadas anteriores con objeto de subsanar el d\u00e9ficit de equipamientos que caracterizaba a Ciempozuelos: en los \u00faltimos a\u00f1os se construyeron, entre otros, el nuevo Ayuntamiento, el Centro parroquial, colegios de educaci\u00f3n infantil y primaria, el instituto Juan Carlos I, la Casa de la Cultura, el Centro de Salud, la Sala Multifuncional o, a nivel ya comarcal, la estaci\u00f3n depuradora del Soto Guti\u00e9rrez. Adem\u00e1s, espacios urbanos de cierta importancia fueron remodelados: en la plaza de Ventura Rodr\u00edguez, por ejemplo, la nueva ordenaci\u00f3n realizada en 1987 redefini\u00f3 los trazados, manteniendo elementos valiosos como el arbolado y el monumento-fuente que se erige en aut\u00e9ntico hito o referencia espacial. Otro ejemplo mucho m\u00e1s reciente es el Parque de San Juan de Dios -enclavado entre la avenida hom\u00f3nima y el paseo de la Estaci\u00f3n, y anta\u00f1o propiedad del hospital masculino- que conserva su masa arb\u00f3rea y se estructura en plataformas a diferente nivel, recuper\u00e1ndose tambi\u00e9n un antiguo kiosco rodeado de un auditorio.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos37.png\" width=\"250\" border=\"0\" \/>Para finalizar, las Normas Subsidiarias son conscientes de la pervivencia de actividades agrarias tradicionales -hasta hace pocos a\u00f1os base de la econom\u00eda local- necesitadas actualmente de apoyo y revitalizaci\u00f3n, por lo que han mantenido el car\u00e1cter especialmente protegido del suelo no urbanizable que forma la vega del Jarama en el t\u00e9rmino municipal, alcanzando tambi\u00e9n esta protecci\u00f3n a v\u00edas pecuarias, descansaderos, caminos rurales y enclaves con importante patrimonio arqueol\u00f3gico. Complemento indispensable de las Normas es la Ley del Parque Regional del Sureste, aprobada por la Asamblea de Madrid en 1994, que, a pesar del escaso desarrollo de su Plan de Ordenaci\u00f3n de Recursos Naturales, deber\u00eda ser la herramienta legal que vele por la integridad de los espacios de valor medioambiental existentes en Ciempozuelos.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ayto-ciempozuelos.org\/images\/stories\/siglos38.png\" width=\"250\" border=\"0\" \/><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 fusion-parallax-none nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: #020724;background-image: url(&quot;http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/FOTO-ok-scaled.jpg&quot;);background-position: left top;background-repeat: no-repeat;padding-top:131px;padding-right:0px;padding-bottom:113px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-no-small-visibility\" style=\"margin-top:2px;margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-blend-mode: overlay;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:rgba(0,0,0,0.33);border-width: 2px 2px 2px 2px;border-color:rgba(255,255,255,0.68);border-style:solid;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-7\" style=\"text-align:center;\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-size: 66px;\" data-fusion-font=\"true\">C\u00f3mo vivieron, gentes, lugares&#8230;<\/span><\/h2>\n<\/div><div class=\"fusion-text fusion-text-8\"><h3 style=\"text-align: center;\"><span style=\"color: #ffffff;\"><span style=\"caret-color: #ffffff;\">Ciempozuelos y sus gentes&#8230;<\/span><\/span><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: #020724;background-position: left top;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion-flex-column fusion-no-small-visibility\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-space-around fusion-content-layout-column\" style=\"background-position:left top;background-blend-mode: overlay;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div ><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"92\" title=\"logo_CREMA\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/logo_CREMA-300x92.png\" class=\"img-responsive wp-image-3963\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/logo_CREMA-200x61.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/logo_CREMA-400x123.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/logo_CREMA-600x184.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/logo_CREMA.png 798w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 300px\" \/><\/span><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-9{width: auto;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-9 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 2%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 0px;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-9{width:100% !important;}.fusion-builder-column-9 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-9{width:100% !important;}.fusion-builder-column-9 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-6{ padding-top : 0px;margin-top : 29px;padding-right : 0px;padding-bottom : 67px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\" style=\"background-color: #ffffff;background-position: left top;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-first fusion-column-inner-bg-wrapper fusion-animated\" style=\"margin-top:0px;margin-bottom:0px;\" data-animationType=\"fadeInLeft\" data-animationDuration=\"0.5\" data-animationOffset=\"100%\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"padding: 0px 0px 0px 0px;\" data-bg-url=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2021\/01\/d9e2f5390c47b992096595f86292b838.jpg\"><div class=\"fusion-clearfix\"><\/div><\/div><span class=\"fusion-column-inner-bg hover-type-zoomin\"><a class=\"fusion-column-anchor\"><span class=\"fusion-column-inner-bg-image\" style=\"background-color:#1a1a1a;background-image: url(&#039;http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2021\/01\/d9e2f5390c47b992096595f86292b838.jpg&#039;);background-position:center top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"><\/span><\/a><\/span><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_3 1_3 fusion-one-third\" style=\"margin-top:0px;margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 10% 10% 10% 10%;\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-4 content-boxes-icon-on-top content-left\" data-animationOffset=\"100%\" style=\"margin-top:45px;margin-bottom:0px;\"><style type=\"text\/css\">.fusion-content-boxes-4 .heading .content-box-heading {color:#333333;}\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-link-icon-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-link-icon-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .fusion-read-more:hover:after,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .fusion-read-more:hover:before,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .fusion-read-more:hover,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-link-icon-hover .icon .circle-no,\n\t\t\t\t\t.fusion-content-boxes-4 .heading .heading-link:hover .content-box-heading {\n\t\t\t\t\t\tcolor: #519c30;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box-hover .icon .circle-no {\n\t\t\t\t\t\tcolor: #519c30 !important;\n\t\t\t\t\t}.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button {background: #519c30;color: #ffffff;}.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button .fusion-button-text {color: #ffffff;}\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon > span {\n\t\t\t\t\t\tbackground-color: #519c30 !important;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box-hover .heading .icon > span {\n\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t}\n\t\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-link-icon-hover.icon-hover-animation-pulsate .fontawesome-icon:after,\n\t\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box-hover.icon-hover-animation-pulsate .fontawesome-icon:after,\n\t\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-link-icon-hover.icon-wrapper-hover-animation-pulsate .icon span:after,\n\t\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box-hover.icon-wrapper-hover-animation-pulsate .icon span:after {\n\t\t\t\t\t\t\t-webkit-box-shadow:0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #519c30, 0 0 0 10px rgba(255,255,255,0.5);\n\t\t\t\t\t\t\t-moz-box-shadow:0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #519c30, 0 0 0 10px rgba(255,255,255,0.5);\n\t\t\t\t\t\t\tbox-shadow: 0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #519c30, 0 0 0 10px rgba(255,255,255,0.5);\n\t\t\t\t\t\t}\n\t\t\t\t\t<\/style><div class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon link-type-text icon-hover-animation-pulsate fusion-animated\" style=\"background-color:rgba(255,255,255,0);\" data-animationType=\"fadeInUp\" data-animationDuration=\"0.8\" data-animationOffset=\"100%\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/salinas-espartinas-turismo-ciempozuelos\/\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"icon\"><i style=\"border-color:rgba(255,255,255,0);border-width:0px;background-color:rgba(5,15,5,0.08);box-sizing:content-box;height:50px;width:50px;line-height:50px;border-radius:50%;color:rgba(168,168,168,0.9);font-size:25px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-mountain fas circle-yes\"><\/i><\/div><h2 class=\"content-box-heading\" style=\"font-size:32px;line-height:37px;\">LAS SALINAS ESPARTINAS<\/h2><\/a><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\" style=\"color:#747474;\">\n<p style=\"font-size: 14px;\" data-fusion-font=\"true\">Declaradas Bien de Inter\u00e9s Cultural, en la categor\u00eda de zona arqueol\u00f3gica.<br \/>\nUna historia de m\u00e1s de 4.000 a\u00f1os.<\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">\n\t\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .heading-link:hover .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box:hover .heading-link .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-4 .fusion-content-box-hover .link-area-box-hover .heading .icon i.circle-yes {\n\t\t\t\t\t\t\tbackground-color: #519c30 !important;\n\t\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t\t}<\/style><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-last fusion-column-inner-bg-wrapper fusion-animated\" style=\"margin-top:0px;margin-bottom:0px;\" data-animationType=\"fadeInLeft\" data-animationDuration=\"0.5\" data-animationOffset=\"100%\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"padding: 0px 0px 0px 0px;\" data-bg-url=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/01\/home_testimonial_and_clients1.jpg\"><div class=\"fusion-clearfix\"><\/div><\/div><span class=\"fusion-column-inner-bg hover-type-zoomin\"><a class=\"fusion-column-anchor\"><span class=\"fusion-column-inner-bg-image\" style=\"background-color:#1a1a1a;background-image: url(&#039;http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/01\/home_testimonial_and_clients1.jpg&#039;);background-position:center top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"><\/span><\/a><\/span><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-8 hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\" style=\"background-color: rgba(255,255,255,0);background-position: left top;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-first\" style=\"margin-top:0px;margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:#ffffff;padding: 10% 10% 10% 10%;\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-5 content-boxes-icon-on-top content-left\" data-animationOffset=\"100%\" style=\"margin-top:45px;margin-bottom:0px;\"><style type=\"text\/css\">.fusion-content-boxes-5 .heading .content-box-heading {color:#333333;}\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-link-icon-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-link-icon-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .fusion-read-more:hover:after,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .fusion-read-more:hover:before,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .fusion-read-more:hover,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-link-icon-hover .icon .circle-no,\n\t\t\t\t\t.fusion-content-boxes-5 .heading .heading-link:hover .content-box-heading {\n\t\t\t\t\t\tcolor: #519c30;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box-hover .icon .circle-no {\n\t\t\t\t\t\tcolor: #519c30 !important;\n\t\t\t\t\t}.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button {background: #519c30;color: #ffffff;}.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button .fusion-button-text {color: #ffffff;}\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon > span {\n\t\t\t\t\t\tbackground-color: #519c30 !important;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box-hover .heading .icon > span {\n\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t}\n\t\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-link-icon-hover.icon-hover-animation-pulsate .fontawesome-icon:after,\n\t\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box-hover.icon-hover-animation-pulsate .fontawesome-icon:after,\n\t\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-link-icon-hover.icon-wrapper-hover-animation-pulsate .icon span:after,\n\t\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box-hover.icon-wrapper-hover-animation-pulsate .icon span:after {\n\t\t\t\t\t\t\t-webkit-box-shadow:0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #519c30, 0 0 0 10px rgba(255,255,255,0.5);\n\t\t\t\t\t\t\t-moz-box-shadow:0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #519c30, 0 0 0 10px rgba(255,255,255,0.5);\n\t\t\t\t\t\t\tbox-shadow: 0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #519c30, 0 0 0 10px rgba(255,255,255,0.5);\n\t\t\t\t\t\t}\n\t\t\t\t\t<\/style><div class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-pulsate fusion-animated\" style=\"background-color:rgba(255,255,255,0);\" data-animationType=\"fadeInUp\" data-animationDuration=\"0.8\" data-animationOffset=\"100%\"><div class=\"heading heading-with-icon icon-left\"><div class=\"icon\"><i style=\"border-color:rgba(255,255,255,0);border-width:0px;background-color:rgba(5,15,5,0.08);box-sizing:content-box;height:50px;width:50px;line-height:50px;border-radius:50%;color:rgba(168,168,168,0.9);font-size:25px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-archway fas circle-yes\"><\/i><\/div><h2 class=\"content-box-heading\" style=\"font-size:32px;line-height:37px;\">LUGARES DE INTER\u00c9S<\/h2><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\" style=\"color:#747474;\">\n<p style=\"font-size: 14px;\" data-fusion-font=\"true\">La econom\u00eda de esta localidad es principalmente agraria de regad\u00edo localizada en la parte este y sureste del t\u00e9rmino municipal (Las Vegas del Jarama).<\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">\n\t\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .heading-link:hover .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box:hover .heading-link .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-5 .fusion-content-box-hover .link-area-box-hover .heading .icon i.circle-yes {\n\t\t\t\t\t\t\tbackground-color: #519c30 !important;\n\t\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t\t}<\/style><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-inner-bg-wrapper fusion-animated\" style=\"margin-top:0px;margin-bottom:0px;\" data-animationType=\"flash\" data-animationDuration=\"0.5\" data-animationOffset=\"100%\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"padding: 0px 0px 0px 0px;\" data-bg-url=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2021\/01\/42336202-3.jpg\"><div class=\"fusion-clearfix\"><\/div><\/div><span class=\"fusion-column-inner-bg hover-type-zoomin\"><a class=\"fusion-column-anchor\"><span class=\"fusion-column-inner-bg-image\" style=\"background-color:#1a1a1a;background-image: url(&#039;http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2021\/01\/42336202-3.jpg&#039;);background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"><\/span><\/a><\/span><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-last\" style=\"margin-top:0px;margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:#ffffff;padding: 10% 10% 10% 10%;\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-6 content-boxes-icon-on-top content-left\" data-animationOffset=\"100%\" style=\"margin-top:45px;margin-bottom:0px;\"><style type=\"text\/css\">.fusion-content-boxes-6 .heading .content-box-heading {color:#333333;}\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-link-icon-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-link-icon-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box-hover .heading .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box-hover .heading .heading-link .content-box-heading,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-link-icon-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .fusion-read-more:hover:after,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .fusion-read-more:hover:before,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .fusion-read-more:hover,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::after,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box-hover.link-area-box .fusion-read-more::before,\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-link-icon-hover .icon .circle-no,\n\t\t\t\t\t.fusion-content-boxes-6 .heading .heading-link:hover .content-box-heading {\n\t\t\t\t\t\tcolor: #519c30;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box-hover .icon .circle-no {\n\t\t\t\t\t\tcolor: #519c30 !important;\n\t\t\t\t\t}.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button {background: #519c30;color: #ffffff;}.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box.link-area-box-hover .fusion-content-box-button .fusion-button-text {color: #ffffff;}\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon > span {\n\t\t\t\t\t\tbackground-color: transparent !important;\n\t\t\t\t\t}\n\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box-hover .heading .icon > span {\n\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t}\n\t\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-link-icon-hover.icon-hover-animation-pulsate .fontawesome-icon:after,\n\t\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box-hover.icon-hover-animation-pulsate .fontawesome-icon:after,\n\t\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-link-icon-hover.icon-wrapper-hover-animation-pulsate .icon span:after,\n\t\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box-hover.icon-wrapper-hover-animation-pulsate .icon span:after {\n\t\t\t\t\t\t\t-webkit-box-shadow:0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #519c30, 0 0 0 10px rgba(255,255,255,0.5);\n\t\t\t\t\t\t\t-moz-box-shadow:0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #519c30, 0 0 0 10px rgba(255,255,255,0.5);\n\t\t\t\t\t\t\tbox-shadow: 0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #519c30, 0 0 0 10px rgba(255,255,255,0.5);\n\t\t\t\t\t\t}\n\t\t\t\t\t<\/style><div class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-pulsate fusion-animated\" style=\"background-color:rgba(255,255,255,0);\" data-animationType=\"fadeInUp\" data-animationDuration=\"0.8\" data-animationOffset=\"100%\"><div class=\"heading heading-with-icon icon-left\"><div class=\"icon\"><i style=\"border-color:rgba(255,255,255,0);border-width:0px;background-color:transparent;box-sizing:content-box;height:88px;width:88px;line-height:88px;border-radius:50%;color:rgba(168,168,168,0.9);font-size:44px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-archway fas circle-yes\"><\/i><\/div><h3 class=\"content-box-heading\" style=\"font-size:32px;line-height:37px;\">LUGARES DE INTER\u00c9S<\/h3><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\" style=\"color:#747474;\">\n<p style=\"font-size: 14px;\" data-fusion-font=\"true\">La econom\u00eda de esta localidad es principalmente agraria de regad\u00edo localizada en la parte este y sureste del t\u00e9rmino municipal (Las Vegas del Jarama).<\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">\n\t\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .heading-link:hover .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box:hover .heading-link .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-link-icon-hover .heading .icon i.circle-yes,\n\t\t\t\t\t\t.fusion-content-boxes-6 .fusion-content-box-hover .link-area-box-hover .heading .icon i.circle-yes {\n\t\t\t\t\t\t\tbackground-color: transparent !important;\n\t\t\t\t\t\t\tborder-color: #519c30 !important;\n\t\t\t\t\t\t}<\/style><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: #020724;background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:calc( 1170px + 0px );margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-9\"><\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-1{margin-top:0px!important;margin-bottom:30px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-title-center fusion-title-text fusion-title-size-one\" style=\"margin-top:0px;margin-bottom:30px;\"><div class=\"title-sep-container title-sep-container-left\"><div class=\"title-sep sep-\" style=\"border-color:#e2e2e2;\"><\/div><\/div><h1 class=\"title-heading-center\" style=\"margin:0;\"><div style=\"text-align: center;\"><span style=\"font-family: var(--h1_typography-font-family); font-size: var(--h1_typography-font-size); font-style: var(--h1_typography-font-style,normal); letter-spacing: var(--h1_typography-letter-spacing); color: #ffffff;\">\u00a0<\/span><\/div>\n<p><span style=\"font-family: var(--h1_typography-font-family); font-size: var(--h1_typography-font-size); font-style: var(--h1_typography-font-style,normal); letter-spacing: var(--h1_typography-letter-spacing); color: #ffffff;\">Galer\u00eda fotogr\u00e1fica<\/span><\/h1><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-\" style=\"border-color:#e2e2e2;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-10\"><h1 style=\"font-size: 22px; text-align: center; color: #828282;\" data-fusion-font=\"true\">Un recorrido fotogr\u00e1fico por nuestra historia&#8230;<\/h1>\n<\/div><div class=\"fusion-image-carousel fusion-image-carousel-fixed lightbox-enabled fusion-carousel-border\"><div class=\"fusion-carousel\" data-autoplay=\"no\" data-columns=\"4\" data-itemmargin=\"13\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-imagesize=\"fixed\"><div class=\"fusion-carousel-positioner\"><ul class=\"fusion-carousel-holder\"><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Antiguo Ayuntamiento2\" aria-label=\"Antiguo Ayuntamiento2\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Antiguo-Ayuntamiento2.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Antiguo-Ayuntamiento2-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Torre Parroquia\" aria-label=\"Torre Parroquia\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Torre-Parroquia.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Torre-Parroquia-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Benito Menni\" aria-label=\"Benito Menni\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Benito-Meni.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Benito-Meni-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Ermita del Consuelo2\" aria-label=\"Ermita del Consuelo2\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Ermita-del-Consuelo2.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Ermita-del-Consuelo2-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Plaza de la Constituci\u00f3n2\" aria-label=\"Plaza de la Constituci\u00f3n2\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Plaza-de-la-Constitucion2.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Plaza-de-la-Constitucion2-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Ventura Rodr\u00edguez\" aria-label=\"Ventura Rodr\u00edguez\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Ventura-Rodriguez.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Ventura-Rodriguez-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Plaza de la Constituci\u00f3n\" aria-label=\"Plaza de la Constituci\u00f3n\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Plaza-de-la-Constitucion.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Plaza-de-la-Constitucion-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Antiguo Ayuntamiento\" aria-label=\"Antiguo Ayuntamiento\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Antiguo-Ayuntamiento.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Antiguo-Ayuntamiento-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Ermita del Consuelo\" aria-label=\"Ermita del Consuelo\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Ermita-del-Consuelo.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Ermita-del-Consuelo-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"encierros\" aria-label=\"encierros\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/encierros.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/encierros-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Antigua f\u00e1brica de cerveza\" aria-label=\"Antigua f\u00e1brica de cerveza\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Antigua-fabrica-de-cerveza.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/Antigua-fabrica-de-cerveza-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Plaza de toros port\u00e1til en Plaza de la Constituci\u00f3n\" aria-label=\"Plaza de toros port\u00e1til en Plaza de la Constituci\u00f3n\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/01\/FB_IMG_1521766252759.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/01\/FB_IMG_1521766252759-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"foto antigua campo ciempozuelos\" aria-label=\"foto antigua campo ciempozuelos\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/01\/FB_IMG_1521289571740.jpg\" target=\"_self\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/01\/FB_IMG_1521289571740-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium\" alt=\"\" \/><\/a><\/div><\/div><\/li><\/ul><div class=\"fusion-carousel-nav\"><span class=\"fusion-nav-prev\"><\/span><span class=\"fusion-nav-next\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-16{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-16 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 0px;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 0px;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-16{width:100% !important;order : 0;}.fusion-builder-column-16 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-16{width:100% !important;order : 0;}.fusion-builder-column-16 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}}<\/style><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-column-inner-bg-wrapper\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"padding: 0% 10% 0% 10%;\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start\" style=\"width:calc( 100% + 0px ) !important;max-width:calc( 100% + 0px ) !important;margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-2 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-flex-start\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 3px 3px 3px 0px;\"><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-nested-column-2{width:100% !important;margin-top : 2px;margin-bottom : 20px;}.fusion-builder-nested-column-2 > .fusion-column-wrapper {padding-top : 3 !important;padding-right : 3 !important;margin-right : 2;padding-bottom : 3 !important;padding-left : 0px !important;margin-left : 2;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-nested-column-2{width:100% !important;order : 0;}.fusion-builder-nested-column-2 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-nested-column-2{width:100% !important;order : 0;}.fusion-builder-nested-column-2 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}}<\/style><\/div><\/div><span class=\"fusion-column-inner-bg hover-type-zoomout\"><a class=\"fusion-column-anchor\"><span class=\"fusion-column-inner-bg-image\" style=\"background-position:center center;background-blend-mode: darken;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"><\/span><\/a><\/span><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-17{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-17 > .fusion-column-wrapper {padding-top : 0% !important;padding-right : 10% !important;margin-right : 0px;padding-bottom : 0% !important;padding-left : 10% !important;margin-left : 0px;}.fusion-flex-container .fusion-row .fusion-builder-column-17 > .fusion-column-inner-bg { margin-right:0px;margin-left:0px; }@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-17{width:100% !important;order : 0;}.fusion-builder-column-17 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}.fusion-flex-container .fusion-row .fusion-builder-column-17 > .fusion-column-inner-bg { margin-right:0px;margin-left:0px; }}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-17{width:100% !important;order : 0;}.fusion-builder-column-17 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}.fusion-flex-container .fusion-row .fusion-builder-column-17 > .fusion-column-inner-bg { margin-right:0px;margin-left:0px; }}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-9{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":114,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[],"class_list":["post-2431","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Una gran historia que contar. El origen de Ciempozuelos se remonta al a\u00f1o 180 a. C. bajo dominaci\u00f3n romana, cuando se estableci\u00f3 el primer n\u00facleo que se conoce. Los colonizadores ser\u00edan oriundos de la ciudad de Puzol y de las isla de Ischia, en el golfo de N\u00e1poles, y la localidad recibi\u00f3 el nombre de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Historia de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Una gran historia que contar. El origen de Ciempozuelos se remonta al a\u00f1o 180 a. C. bajo dominaci\u00f3n romana, cuando se estableci\u00f3 el primer n\u00facleo que se conoce. Los colonizadores ser\u00edan oriundos de la ciudad de Puzol y de las isla de Ischia, en el golfo de N\u00e1poles, y la localidad recibi\u00f3 el nombre de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-27T12:07:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-29T12:22:15+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Historia de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Una gran historia que contar. El origen de Ciempozuelos se remonta al a\u00f1o 180 a. C. bajo dominaci\u00f3n romana, cuando se estableci\u00f3 el primer n\u00facleo que se conoce. Los colonizadores ser\u00edan oriundos de la ciudad de Puzol y de las isla de Ischia, en el golfo de N\u00e1poles, y la localidad recibi\u00f3 el nombre de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/historiadeciempozuelos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/historiadeciempozuelos\\\/#listItem\",\"name\":\"Historia de Ciempozuelos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/historiadeciempozuelos\\\/#listItem\",\"position\":2,\"name\":\"Historia de Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/historiadeciempozuelos\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/historiadeciempozuelos\\\/\",\"name\":\"Historia de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"Una gran historia que contar. El origen de Ciempozuelos se remonta al a\\u00f1o 180 a. C. bajo dominaci\\u00f3n romana, cuando se estableci\\u00f3 el primer n\\u00facleo que se conoce. Los colonizadores ser\\u00edan oriundos de la ciudad de Puzol y de las isla de Ischia, en el golfo de N\\u00e1poles, y la localidad recibi\\u00f3 el nombre de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/historiadeciempozuelos\\\/#breadcrumblist\"},\"datePublished\":\"2019-02-27T12:07:35+01:00\",\"dateModified\":\"2025-10-29T13:22:15+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Historia de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"Una gran historia que contar. El origen de Ciempozuelos se remonta al a\u00f1o 180 a. C. bajo dominaci\u00f3n romana, cuando se estableci\u00f3 el primer n\u00facleo que se conoce. Los colonizadores ser\u00edan oriundos de la ciudad de Puzol y de las isla de Ischia, en el golfo de N\u00e1poles, y la localidad recibi\u00f3 el nombre de","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/#listItem","name":"Historia de Ciempozuelos"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/#listItem","position":2,"name":"Historia de Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/","name":"Historia de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"Una gran historia que contar. El origen de Ciempozuelos se remonta al a\u00f1o 180 a. C. bajo dominaci\u00f3n romana, cuando se estableci\u00f3 el primer n\u00facleo que se conoce. Los colonizadores ser\u00edan oriundos de la ciudad de Puzol y de las isla de Ischia, en el golfo de N\u00e1poles, y la localidad recibi\u00f3 el nombre de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/#breadcrumblist"},"datePublished":"2019-02-27T12:07:35+01:00","dateModified":"2025-10-29T13:22:15+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Historia de Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"Una gran historia que contar. El origen de Ciempozuelos se remonta al a\u00f1o 180 a. C. bajo dominaci\u00f3n romana, cuando se estableci\u00f3 el primer n\u00facleo que se conoce. Los colonizadores ser\u00edan oriundos de la ciudad de Puzol y de las isla de Ischia, en el golfo de N\u00e1poles, y la localidad recibi\u00f3 el nombre de","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/","article:published_time":"2019-02-27T12:07:35+00:00","article:modified_time":"2025-10-29T12:22:15+00:00","twitter:card":"summary","twitter:title":"Historia de Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"Una gran historia que contar. El origen de Ciempozuelos se remonta al a\u00f1o 180 a. C. bajo dominaci\u00f3n romana, cuando se estableci\u00f3 el primer n\u00facleo que se conoce. Los colonizadores ser\u00edan oriundos de la ciudad de Puzol y de las isla de Ischia, en el golfo de N\u00e1poles, y la localidad recibi\u00f3 el nombre de"},"aioseo_meta_data":{"post_id":"2431","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"#aioseo-web-page-63f881d70a438","slug":"web-page","graphName":"WebPage","label":"P\u00e1gina web","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2022-06-30 09:42:16","updated":"2025-10-29 12:23:14","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHistoria de Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Historia de Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/historiadeciempozuelos\/"}],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 12:13:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/pages\/2431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=2431"}],"version-history":[{"count":105,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/pages\/2431\/revisions"}],"predecessor-version":[{"id":42118,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/pages\/2431\/revisions\/42118"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=2431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=2431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=2431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}